{"id":114953,"date":"2023-02-07T19:28:38","date_gmt":"2023-02-08T00:28:38","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=114953"},"modified":"2023-02-07T19:28:42","modified_gmt":"2023-02-08T00:28:42","slug":"camara-de-diputados-pri-busca-penas-mas-severas-para-narcomenudistas","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/nacionales\/camara-de-diputados-pri-busca-penas-mas-severas-para-narcomenudistas\/","title":{"rendered":"C\u00e1mara de Diputados: PRI busca penas m\u00e1s severas para narcomenudistas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La\u00a0<strong>fracci\u00f3n parlamentaria<\/strong>\u00a0del\u00a0PRI\u00a0en la\u00a0C\u00e1mara de Diputados\u00a0busca reformas para que los\u00a0narcomenudistas, despu\u00e9s de su vinculaci\u00f3n a proceso, no tengan tan f\u00e1cil solicitar la suspensi\u00f3n condicional, la cual les permite salir de prisi\u00f3n antes de tiempo para volver a delinquir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de una iniciativa presentada por el&nbsp;<strong>diputado priista Jos\u00e9 Antonio Guti\u00e9rrez&nbsp;<\/strong>se buscan reformas a la Ley General de Salud y al C\u00f3digo Nacional de Procedimientos Penales para ampliar el tiempo de prisi\u00f3n al que posea alg\u00fan narc\u00f3tico de los se\u00f1alados en la Ley y se acredite el il\u00edcito si se aseguran objetos o instrumentos que sirven para la comisi\u00f3n de este hecho delictivo, imponer de cuatro a siete a\u00f1os de prisi\u00f3n y de&nbsp;<strong>100 a 350 d\u00edas de multa&nbsp;<\/strong>por este delito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aseguran que M\u00e9xico vive una de las peores crisis&nbsp;en materia de seguridad p\u00fablica<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En su argumentaci\u00f3n, la propuesta se\u00f1ala que&nbsp;<strong>M\u00e9xico&nbsp;<\/strong>vive una de las&nbsp;<strong>peores crisis de su historia en materia de seguridad p\u00fablica<\/strong>, relacionada con el<strong>&nbsp;narcotr\u00e1fico<\/strong>, toda vez que los resultados de la estrategia del Gobierno federal para mitigar los niveles de violencia en el pa\u00eds han sido insuficientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta crisis est\u00e1 directamente relacionada con el fortalecimiento del crimen organizado en el pa\u00eds ligado al narcotr\u00e1fico, las divisiones al interior de los principales<strong>&nbsp;c\u00e1rteles de tr\u00e1fico de drogas<\/strong>&nbsp;y la diversificaci\u00f3n de los mismos. Todo esto ha desembocado en una lucha sangrienta por el control de plazas clave para las rutas del tr\u00e1fico\u201d, se\u00f1al\u00f3.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/heraldodemexico.com.mx\/u\/fotografias\/m\/2023\/2\/6\/f768x1-667804_667931_13.png\" alt=\"\"\/><figcaption>El diputado priista Jos\u00e9 Antonio Guti\u00e9rrez Foto: Twitter @GPPRIDiputados<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Proponen que narcomenudistas no puedan solicitar suspensi\u00f3n condicional<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La reforma y adici\u00f3n al art\u00edculo 476 de la&nbsp;<strong>Ley General de Salud<\/strong>&nbsp;establece que se entender\u00e1 acreditado este hecho, la posesi\u00f3n de comercio con fines de venta o suministro, a\u00fan gratuitamente, con la forma de presentaci\u00f3n del narc\u00f3tico en diversas dosis, como tambi\u00e9n se puede acreditar con el aseguramiento de objetos o instrumentos que sirven para la comisi\u00f3n de este hecho, como lo son b\u00e1sculas grameras, numerario, bolsas para dosificar,&nbsp;<strong>narc\u00f3tico<\/strong>, entre otros que permitan la ejecuci\u00f3n de este hecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, en el<strong>&nbsp;C\u00f3digo Nacional de Procedimientos Penales,<\/strong>&nbsp;propone reformas a los art\u00edculos 192 y 198 para que quede prohibida cualquier disposici\u00f3n en contrario por parte de la federaci\u00f3n o entidades federativas, en donde se autorice un beneficio equivalente al de la suspensi\u00f3n condicional a proceso cuando exista un registro o antecedente en la temporalidad establecida en esta fracci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la iniciativa se se\u00f1ala que los&nbsp;<strong>narcomenudistas detenidos<\/strong>, constantemente en todo el territorio nacional, capturados por las autoridades, inician su vinculaci\u00f3n a proceso y&nbsp;<strong>salen libres despu\u00e9s de cierto tiempo<\/strong>, para volver a delinquir, casi siempre, en venta de narc\u00f3ticos, porque se refugian en la figura de suspensi\u00f3n condicional a proceso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0fracci\u00f3n parlamentaria\u00a0del\u00a0PRI\u00a0en la\u00a0C\u00e1mara de Diputados\u00a0busca reformas para que los\u00a0narcomenudistas, despu\u00e9s de su vinculaci\u00f3n a proceso, no tengan tan f\u00e1cil solicitar la suspensi\u00f3n condicional, la cual les permite salir de prisi\u00f3n antes de tiempo para volver a delinquir. A trav\u00e9s de una iniciativa presentada por el&nbsp;diputado priista Jos\u00e9 Antonio Guti\u00e9rrez&nbsp;se buscan reformas a la Ley General [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":114954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-114953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/114953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=114953"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/114953\/revisions"}],"predecessor-version":[{"id":114955,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/114953\/revisions\/114955"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/114954"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=114953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=114953"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=114953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}