{"id":114957,"date":"2023-02-07T19:32:51","date_gmt":"2023-02-08T00:32:51","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=114957"},"modified":"2023-02-07T19:32:55","modified_gmt":"2023-02-08T00:32:55","slug":"mas-de-570-mil-personas-reciben-pensiones-y-programas-de-bienestar-en-comunidades-del-tramo-4-del-tren-maya","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/destacadas\/mas-de-570-mil-personas-reciben-pensiones-y-programas-de-bienestar-en-comunidades-del-tramo-4-del-tren-maya\/","title":{"rendered":"M\u00e1s de 570 mil personas reciben Pensiones y Programas de Bienestar en comunidades del tramo 4 del Tren Maya"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">De manera directa y sin intermediarios, el Gobierno de M\u00e9xico avanza en la entrega de Pensiones y Programas de Bienestar en el tramo 4 del Tren Maya, que va de Kantunil a Benito Ju\u00e1rez en el estado de Yucat\u00e1n, donde a la fecha se beneficia a 574 mil 597 personas con inversi\u00f3n social anual de 13 mil 522 millones de pesos, inform\u00f3 la secretaria de Bienestar, Ariadna Montiel Reyes, en la conferencia de prensa matutina del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Sal\u00f3n de la Tesorer\u00eda de Palacio Nacional, explic\u00f3 que, en Yucat\u00e1n, se aplica de forma integral toda la pol\u00edtica de Bienestar del Gobierno de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al abundar sobre la distribuci\u00f3n de las Pensiones y Programas de Bienestar, la secretaria Ariadna Montiel inform\u00f3 que la Pensi\u00f3n para el Bienestar de las Personas Adultas Mayores se entrega a 208 mil 250 derechohabientes y la Pensi\u00f3n para el Bienestar de las Personas con Discapacidad a 28 mil 672.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/heraldodemexico.com.mx\/u\/fotografias\/m\/2023\/2\/6\/f768x1-667496_667623_5050.jpeg\" alt=\"\"\/><figcaption>Estos recursos est\u00e1n garantizados por parte de las autoridades. FOTO: Especial.&nbsp;<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Programa de Apoyo para Ni\u00f1as y Ni\u00f1os, Hijos de Madres Trabajadoras beneficia a tres mil 529 personas; y Sembrando Vida a 10 mil 157 sembradoras y sembradores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, las Becas \u201cBenito Ju\u00e1rez\u201d de la SEP se entregan a 148 mil 617 estudiantes en nivel b\u00e1sico; 77 mil 544 en medio superior; y 15 mil 621 en superior. La Escuela es Nuestra (LEN) entrega a trav\u00e9s de la SEP recursos directos a dos mil 533 centros educativos para la mejora de planteles; y el programa J\u00f3venes Construyendo el Futuro de la STPS llega a cinco mil 629 personas que se capacitan para el trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al impulso a la productividad, el programa de pesca se entrega a 11 mil 703 beneficiarios y Producci\u00f3n para el Bienestar a 39 mil 810 a trav\u00e9s de Sader; Tandas para el Bienestar a 21 mil 737 mujeres y hombres emprendedores y vivienda beneficia a 795 familias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En&nbsp;cuanto al Fondo de Aportaciones para la Infraestructura Social (FAIS), la inversi\u00f3n social anual es de dos mil 710 millones de pesos; as\u00ed como se tienen construidas 91 sucursales del Banco del Bienestar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este informe es el cuarto de siete que se dar\u00e1n a conocer cada lunes en la conferencia matutina del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, a fin de que la ciudadan\u00eda est\u00e9 enterada sobre las acciones del Gobierno de M\u00e9xico para su bienestar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: heraldodemexico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De manera directa y sin intermediarios, el Gobierno de M\u00e9xico avanza en la entrega de Pensiones y Programas de Bienestar en el tramo 4 del Tren Maya, que va de Kantunil a Benito Ju\u00e1rez en el estado de Yucat\u00e1n, donde a la fecha se beneficia a 574 mil 597 personas con inversi\u00f3n social anual de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":114958,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-114957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/114957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=114957"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/114957\/revisions"}],"predecessor-version":[{"id":114959,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/114957\/revisions\/114959"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/114958"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=114957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=114957"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=114957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}