{"id":145534,"date":"2025-09-24T09:16:08","date_gmt":"2025-09-24T14:16:08","guid":{"rendered":"https:\/\/elcuartopoder.com.mx\/nw\/?p=145534"},"modified":"2025-09-24T09:17:40","modified_gmt":"2025-09-24T14:17:40","slug":"narcolegisladores","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/opinion\/narcolegisladores\/","title":{"rendered":"Narcolegisladores"},"content":{"rendered":"\n<p>La diputada federal de Morena, Hilda Araceli Brown Figueredo, est\u00e1 se\u00f1alada en documentos del Departamento del Tesoro de Estados Unidos, por presuntos v\u00ednculos con la fracci\u00f3n de Los Mayos del C\u00e1rtel de Sinaloa.<\/p>\n\n\n\n<p>El caso de la diputada federal de Morena, Hilda Araceli Brown Figueredo, quien est\u00e1 se\u00f1alada en documentos del Departamento del Tesoro de Estados Unidos, en particular de la Oficina de Control de Activos Extranjeros (OFAC), por presuntos v\u00ednculos con la fracci\u00f3n de Los Mayos del C\u00e1rtel de Sinaloa. Se trata de otro caso m\u00e1s que ratifica la aseveraci\u00f3n de que el crimen organizado ha permeado en las estructuras del poder pol\u00edtico de nuestro pa\u00eds.<\/p>\n\n\n\n<p>La tambi\u00e9n exalcaldesa de Playas de Rosarito, BC, formaba parte de la \u201cred de Rosarito\u201d, que de acuerdo a la OFAC, se trata de un entramado pol\u00edtico y empresarial que serv\u00eda como brazo de protecci\u00f3n y financiamiento para la organizaci\u00f3n criminal.<\/p>\n\n\n\n<p>Las autoridades estadounidenses se\u00f1alan que Brown facilit\u00f3 la penetraci\u00f3n del c\u00e1rtel en estructuras pol\u00edticas locales. Esta red, vinculada a negocios de bares, restaurantes y bienes ra\u00edces en Rosarito, presuntamente era utilizada para lavar dinero y proteger cargamentos de droga hacia Estados Unidos.<\/p>\n\n\n\n<p>La sanci\u00f3n impuesta por la OFAC a la legisladora federal de Morena implica que todos sus activos bajo jurisdicci\u00f3n estadounidense quedan congelados y que ciudadanos y compa\u00f1\u00edas de Estados Unidos tienen prohibido realizar transacciones con ella. Por su parte, la Unidad de Inteligencia Financiera bloque\u00f3 las cuentas bancarias de Hilda Araceli Brown Figueredo.<\/p>\n\n\n\n<p>La infiltraci\u00f3n de los delincuentes a la n\u00f3mina del ayuntamiento de Rosarito permit\u00eda extorsionar a los empresarios y, en general, a la poblaci\u00f3n que estaba sometida bajo dos fuegos: la de los criminales y la represi\u00f3n gubernamental municipal, para exprimirlos en sus recursos econ\u00f3micos.<\/p>\n\n\n\n<p>El retiro del visado norteamericano a la gobernadora morenista de Baja California, Marina del Pilar \u00c1vila, y a su esposo, Carlos Torres, hace cuatro meses, marca esa tendencia inercial de la connivencia de las autoridades estatales y municipales con los malosos; adem\u00e1s, ratific\u00f3 la idea que tiene el gobierno de Estados Unidos de que en M\u00e9xico gobiernan los c\u00e1rteles de la droga, tal como lo ha aseverado el mismo presidente Donald Trump.<\/p>\n\n\n\n<p>El esc\u00e1ndalo del huachicoleo fiscal y el caso de Hern\u00e1n Berm\u00fadez Requena, exsecretario de Seguridad P\u00fablica en tiempos de Ad\u00e1n Augusto L\u00f3pez, son parte de todo el entramado criminal nacional que se enquist\u00f3 en parte de los tres niveles de gobierno en el sexenio de L\u00f3pez Obrador y que prendi\u00f3 las alertas en la Casa Blanca por tratarse de una amenaza a su seguridad interior.<\/p>\n\n\n\n<p>Como se aprecia, estamos ante un monstruo de mil cabezas que se ha ido destapando conforme el gobierno norteamericano abre la caja de Pandora sobre los narcoterroristas y pol\u00edticos mexicanos y su impacto en la Uni\u00f3n Americana.<\/p>\n\n\n\n<p>Desde luego, hay que darle cierto m\u00e9rito al gobierno de la presidenta Sheinbaum en esta cruzada contra la delincuencia; sin embargo, si no presionara en el nivel que lo est\u00e1 haciendo su contraparte gringa, pues las cosas seguir\u00edan como estaban en la anterior administraci\u00f3n.<\/p>\n\n\n\n<p>Es necesario que la jefa del Poder Ejecutivo mande al Congreso de la Uni\u00f3n diversas iniciativas de reforma para generar todo un esquema jur\u00eddico para evitar que los servidores p\u00fablicos se inmiscuyan en actividades criminales. No bastan las sanciones que se contemplan en los c\u00f3digos penales, ni las declaraciones patrimoniales y menos las instituciones que los vigilan como la propia FGR o la UIF. Se requieren nuevos esquemas punitivos que blinden a todo el aparato pol\u00edtico para impedir que sean infiltrados por los c\u00e1rteles de la droga.<\/p>\n\n\n\n<p>El caso de la diputada federal morenista Hilda Brown no es el \u00fanico y pronto sabremos de otros diputados y senadores del oficialismo que est\u00e1n en franca connivencia con los criminales. Vamos, en este momento ya resulta emblem\u00e1tico el caso del l\u00edder de los senadores de Morena, Ad\u00e1n Augusto L\u00f3pez, por su estrecha relaci\u00f3n con el exl\u00edder del c\u00e1rtel de La Barredora, Hern\u00e1n Berm\u00fadez, y con el tema del huachicol fiscal.<\/p>\n\n\n\n<p>Ante tantos casos de corrupci\u00f3n del sexenio pasado que han salido a la luz, es inconcebible que Andr\u00e9s Manuel L\u00f3pez Obrador no conociera las trapacer\u00edas de algunos de sus colaboradores, como el almirante secretario de Marina, Rafael Ojeda Dur\u00e1n, y sus sobrinos. Adem\u00e1s, las correr\u00edas de sus v\u00e1stagos aparecen en el expediente que obra en poder de la Fiscal\u00eda General de la Rep\u00fablica (FGR) en torno al huachicoleo.<\/p>\n\n\n\n<p>En las ma\u00f1aneras se aprecia que diario la presidenta Claudia Sheinbaum intenta encubrir y cambiar la narrativa de que hay varios p\u00e1jaros de cuenta en las filas de los servidores p\u00fablicos involucrados en actividades criminales; sin embargo, no es posible tapar el sol con un dedo.<\/p>\n\n\n\n<p>Fuente: EF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La diputada federal de Morena, Hilda Araceli Brown Figueredo, est\u00e1 se\u00f1alada en documentos del Departamento del Tesoro de Estados Unidos, por presuntos v\u00ednculos con la fracci\u00f3n de Los Mayos del C\u00e1rtel de Sinaloa. El caso de la diputada federal de Morena, Hilda Araceli Brown Figueredo, quien est\u00e1 se\u00f1alada en documentos del Departamento del Tesoro de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":145538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-145534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/145534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=145534"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/145534\/revisions"}],"predecessor-version":[{"id":145536,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/145534\/revisions\/145536"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/145538"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=145534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=145534"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=145534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}