{"id":149848,"date":"2026-09-02T06:56:25","date_gmt":"2026-09-02T11:56:25","guid":{"rendered":"https:\/\/elcuartopoder.com.mx\/nw\/?p=149848"},"modified":"2026-09-02T06:56:27","modified_gmt":"2026-09-02T11:56:27","slug":"lindsay-clancy-sigue-sin-veredicto-el-jurado-no-consigue-decidir-si-es-culpable-de-matar-a-sus-tres-hijos","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/policiacas\/lindsay-clancy-sigue-sin-veredicto-el-jurado-no-consigue-decidir-si-es-culpable-de-matar-a-sus-tres-hijos\/","title":{"rendered":"Lindsay Clancy sigue sin veredicto: el jurado no consigue decidir si es culpable de matar a sus tres hijos"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El juez ha ordenado al jurado popular que contin\u00fae deliberando tras no llegar a una decisi\u00f3n un\u00e1nime<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lindsay Clacy, acusada de matar a sus tres hijos peque\u00f1os en 2023, sigue sin un veredicto en su juicio. Los miembros del jurado popular han notificado este martes al juez del caso que\u00a0<strong>no han conseguido llegar a una decisi\u00f3n un\u00e1nime<\/strong>\u00a0sobre si condenar\u00a0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jurado popular no consigue decidir si\u00a0<strong>Lindsay Clancy<\/strong>, que admiti\u00f3 haber asesinado a sus tres hijos, es culpable o no. El caso ya se ha convertido en el juicio m\u00e1s medi\u00e1tico del a\u00f1o. Ahora, toca seguir deliberando, en la misma sala donde la acusada\u00a0<strong>rompi\u00f3 a llorar<\/strong>\u00a0tras escuchar el testimonio del m\u00e9dico forense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 24 de enero de 2023,&nbsp;<strong>Clancey estrangul\u00f3 a sus tres hijos de cinco, tres a\u00f1os y ocho meses<\/strong>&nbsp;en el s\u00f3tano de su casa en Massachusetts, mientras su esposo hac\u00eda la compra. Despu\u00e9s, trat\u00f3 de suicidarse sin \u00e9xito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien ella admite el asesinato, se declara inocente, alegando sufrir&nbsp;<strong>una psicosis posparto agravada<\/strong>&nbsp;<strong>por una err\u00f3nea medicaci\u00f3n<\/strong>&nbsp;que le recetaron para la depresi\u00f3n y la bipolaridad. \u00abSi alguien tiene trastorno bipolar, no se le puede administrar un antidepresivo\u00bb, ha sostenido su abogado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De hecho, el letrado critica la atenci\u00f3n psiqui\u00e1trica que recibi\u00f3, mientras que la acusaci\u00f3n sostiene que era plenamente consciente de lo que hac\u00eda. \u00abActu\u00f3 de&nbsp;<strong>forma intencionada, racional y r\u00e1pida para lograr un objetivo muy concreto: matar<\/strong>\u00ab, ha asegurado durante el juicio la fiscal Jennifer Sprague.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, los testigos han declarado que su salud mental&nbsp;<strong>se habr\u00eda deteriorado tras su \u00faltimo parto<\/strong>. Incluso, relatan que les lleg\u00f3 a comentar que ten\u00eda pensamientos impulsivos de atacar a sus hijos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo un caso que ha llamado tanto la atenci\u00f3n de la sociedad estadounidense, que ha generado\u00a0<strong>una gran divisi\u00f3n entre quienes la consideran una vil asesina y quienes creen que el sistema sanitario ha fallado<\/strong>\u00a0con su diagn\u00f3stico. Misma divisi\u00f3n que hay ahora en la sala del tribunal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: ABC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El juez ha ordenado al jurado popular que contin\u00fae deliberando tras no llegar a una decisi\u00f3n un\u00e1nime Lindsay Clacy, acusada de matar a sus tres hijos peque\u00f1os en 2023, sigue sin un veredicto en su juicio. Los miembros del jurado popular han notificado este martes al juez del caso que\u00a0no han conseguido llegar a una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":149849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-149848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiacas"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/149848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=149848"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/149848\/revisions"}],"predecessor-version":[{"id":149850,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/149848\/revisions\/149850"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/149849"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=149848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=149848"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=149848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}