{"id":149854,"date":"2026-09-02T06:59:14","date_gmt":"2026-09-02T11:59:14","guid":{"rendered":"https:\/\/elcuartopoder.com.mx\/nw\/?p=149854"},"modified":"2026-09-02T06:59:16","modified_gmt":"2026-09-02T11:59:16","slug":"anthropic-destruyo-millones-de-libros-con-los-que-alimento-su-ia","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/varios\/anthropic-destruyo-millones-de-libros-con-los-que-alimento-su-ia\/","title":{"rendered":"Anthropic destruy\u00f3 millones de libros con los que aliment\u00f3 su IA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En 2024, la empresa de inteligencia artificial (IA) Anthropic puso en marcha una estrategia consistente en adquirir millones de libros, deshojarlos, escanearlos y utilizar su contenido para alimentar modelos de IA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los detalles de la iniciativa, llamada Proyecto Panam\u00e1, se mantuvieron en secreto hasta que un juez de distrito en Estados Unidos hizo p\u00fablicos m\u00e1s de 4 mil p\u00e1ginas de documentos de una demanda por derechos de autor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista con&nbsp;<em>La Jornada,&nbsp;<\/em>Ismael Everardo B\u00e1rcenas Pati\u00f1o, responsable del Laboratorio de Inteligencia Artificial Microsoft de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM), explic\u00f3 que modelos de IA, como los que dan soporte a chatbots, necesitan grandes cantidades de informaci\u00f3n para responder consultas de \u00e1mbitos de la salud, la educaci\u00f3n y otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi lo entrenamos con un libro sobre medicina, todos esos datos se cargan en el modelo y entonces es capaz de utilizar esa informaci\u00f3n para inferir sobre alguna consulta\u201d, explic\u00f3 el especialista.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">En busca de nuevas fuentes de entrenamiento<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista por separado, Roc\u00edo Aldeco P\u00e9rez, especialista en criptograf\u00eda, cadena de bloques y sistemas distribuidos, considera que lo ocurrido con Anthropic es un s\u00edntoma de que para entrenar a la IA est\u00e1n buscando nuevas fuentes de informaci\u00f3n m\u00e1s all\u00e1 de los contenidos disponibles en Internet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHay libros antiguos que nunca fueron digitalizados; entonces su informaci\u00f3n nunca se us\u00f3 para ese entrenamiento, recurrir a ellos es una manera de ver si esos datos mejorar\u00edan el modelo de aprendizaje que ya se tiene.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los documentos legales hechos p\u00fablicos y revisados por&nbsp;<em>The Washington Post&nbsp;<\/em>revelaron que Anthropic hab\u00eda recurrido a libros y otros contenidos de sitios que distribu\u00edan contenidos sin respetar derechos de autor. Seg\u00fan esos registros, Anthropic compr\u00f3 millones de libros usados. El plan contemplaba cortar los lomos de los ejemplares para escanear sus p\u00e1ginas y, posteriormente, entregarlos a una empresa de reciclaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aldeco P\u00e9rez y B\u00e1rcenas Pati\u00f1o coincidieron en que, en medio de la competencia acelerada por desarrollar modelos de IA, uno de los principales desaf\u00edos es el uso de obras protegidas por derechos de autor. \u201cCuando escribes un libro esperas venderlo y ganar dinero para seguir escribiendo. Aqu\u00ed se usa de maneras que no puedo decir ilegales, pero que tampoco son legales. Es algo que sucede en un espacio gris de la legislaci\u00f3n\u201d, apunt\u00f3 Aldeco P\u00e9rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstos modelos basados principalmente en redes neuronales necesitan mucha informaci\u00f3n para entrenarse. El tema aqu\u00ed es que estos modelos eventualmente lucran; entonces, ser\u00eda pertinente evaluar si se tendr\u00eda que pagar derecho de autor\u201d, agreg\u00f3 B\u00e1rcenas Pati\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El juez de distrito William Alsup dictamin\u00f3 que Anthropic pod\u00eda utilizar libros adquiridos legalmente para entrenar a sus modelos de IA, ya que \u00e9stos usaban el material de forma transformadora. Compar\u00f3 el proceso de entrenamiento de IA con el de profesores que ense\u00f1an a escribir bien. Sin embargo, el juez dej\u00f3 abierta la disputa sobre los libros obtenidos de fuentes que infring\u00edan derechos de autor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lejos de nuestra realidad<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para B\u00e1rcenas Pati\u00f1o, M\u00e9xico est\u00e1 lejos de ver una operaci\u00f3n como Proyecto Panam\u00e1, debido a que el pa\u00eds no cuenta con la infraestructura necesaria para emprender un proceso como \u00e9se, que requiere centros de datos de alta potencia, equipos especializados y grandes capacidades de c\u00f3mputo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, dijo que el pa\u00eds tiene grandes vol\u00famenes de informaci\u00f3n que podr\u00edan ser de inter\u00e9s para empresas extranjeras que desarrollan modelos de IA. Entre ellos, mencion\u00f3 la producci\u00f3n editorial, los contenidos disponibles p\u00fablicamente en Internet, la informaci\u00f3n que los usuarios generan en plataformas digitales y datos gubernamentales de acceso p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto B\u00e1rcenas Pati\u00f1o como Aldeco P\u00e9rez plantean que, en el contexto de la competencia por la IA generativa, M\u00e9xico debe apostar por desarrollar tecnolog\u00eda propia y crear una regulaci\u00f3n que establezca l\u00edmites claros para el uso de obras y datos en entrenamiento de modelos de inteligencia artificial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cC\u00f3mo vamos a legislar y c\u00f3mo vamos a proteger la soberan\u00eda de nuestros pa\u00edses frente a esta situaci\u00f3n son las conversaciones que debemos dar en universidades, empresas y gobierno\u201d, concluy\u00f3 Aldeco P\u00e9rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: lajornada<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2024, la empresa de inteligencia artificial (IA) Anthropic puso en marcha una estrategia consistente en adquirir millones de libros, deshojarlos, escanearlos y utilizar su contenido para alimentar modelos de IA. Los detalles de la iniciativa, llamada Proyecto Panam\u00e1, se mantuvieron en secreto hasta que un juez de distrito en Estados Unidos hizo p\u00fablicos m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":149855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-149854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varios"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/149854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=149854"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/149854\/revisions"}],"predecessor-version":[{"id":149856,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/149854\/revisions\/149856"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/149855"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=149854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=149854"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=149854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}