{"id":84379,"date":"2020-10-26T13:04:48","date_gmt":"2020-10-26T18:04:48","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=84379"},"modified":"2020-10-26T13:04:50","modified_gmt":"2020-10-26T18:04:50","slug":"samuel-l-jackson-bradley-cooper-y-trece-actores-que-son-los-mas-taquilleros-de-hollywood","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/entretenimiento\/espectaculos\/samuel-l-jackson-bradley-cooper-y-trece-actores-que-son-los-mas-taquilleros-de-hollywood\/","title":{"rendered":"Samuel L. Jackson, Bradley Cooper y trece actores que son los m\u00e1s taquilleros de Hollywood"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico.- Sagas de \u00e9xito como las de <strong><em>El se\u00f1or de los anillos<\/em><\/strong>,\u00a0<strong><em>Harry Potter<\/em><\/strong>\u00a0o las\u00a0<strong>pel\u00edculas de Marvel<\/strong>\u00a0han hecho historia en el s\u00e9ptimo arte. Y no por su repercusi\u00f3n mundial y argumentos que est\u00e1n en boca de todos, que tambi\u00e9n, sino por las cantidades imposibles de\u00a0<strong>dinero<\/strong>\u00a0que han ofrecido a actores como Samuel L. Jackson, Robert Downey Jr. o Harrison Ford.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando pensamos en los actores m\u00e1s taquilleros de Hollywood, se nos vienen a la cabeza aquellos que han conseguido que una pel\u00edcula sea un taquillazo: Tom Cruise en&nbsp;<em>Misi\u00f3n Imposible<\/em>&nbsp;o en&nbsp;<em>La guerra de los mundos<\/em>, Tom Hanks en&nbsp;<em>El c\u00f3digo Da Vinci<\/em>&nbsp;o en&nbsp;<em>Atr\u00e1pame si puedes<\/em>\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, estos son casos aislados. El cine de la \u00faltima era ha descubierto que sagas como&nbsp;<em>Avengers<\/em>&nbsp;o&nbsp;<em>La guerra de las galaxias<\/em>&nbsp;son las que realmente consiguen montar a los actores en el d\u00f3lar. A continuaci\u00f3n dejamos la lista, de menor a mayor, de los 15 actores m\u00e1s taquilleros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>15.- BRADLEY COOPER<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 3 mil 626 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>Avengers: Infinity War<\/em>&nbsp;(2018, Anthony Russo, Joe Russo)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>14.- IAN MCKELLEN<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 3 mil 654 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>La bella y la bestia<\/em>&nbsp;(2017, Bill Condon)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>13.- JOHNNY DEPP<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 3 mil 687 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>Piratas del Caribe: El cofre del hombre muerto<\/em>&nbsp;(2006, Gore Verbinski)<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.sinembargo.mx\/wp-content\/uploads\/2020\/10\/befunky-project-2020-10-24t173643-257.jpg\" alt=\"\" class=\"wp-image-3882882\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Depp se enfrent\u00f3 a diversas pol\u00e9micas luego de su salida de la famosa saga. Foto: Especial<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>12.- IDRIS ELBA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 3 mil 688 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>Avengers: Infinity War<\/em>&nbsp;(2018, Anthony Russo, Joe Russo)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>11.- STANLEY TUCCI<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 3 mil 776 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>La bella y la bestia<\/em>&nbsp;(2017, Bill Condon)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10.- TOM CRUISE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 3 mil 786 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>La guerra de los mundos<\/em>&nbsp;(2005, Steven Spielberg)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9.- EDDIE MURPHY<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 3 mil 811 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>Shrek 2<\/em>&nbsp;(2004)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8.- ANTHONY DANIELS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 4 mil 40 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>Star Wars: Episodio VII \u2013 El despertar de la Fuerza<\/em>&nbsp;(2015, J.J. Abrams)<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.sinembargo.mx\/wp-content\/uploads\/2020\/10\/befunky-project-2020-10-24t173832-371.jpg\" alt=\"\" class=\"wp-image-3882884\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Parte del elenco de Avengers destaca entre los actores m\u00e1s taquilleros. Foto: Especial<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7.- ANDY SERKIS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 4 mil 358 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera: S<em>tar Wars: Episodio VII \u2013 El despertar de la Fuerza<\/em>&nbsp;(2015, J.J. Abrams)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6.- SCARLETT JOHANSSON<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 4 mil 386 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>Avengers: Infinity War<\/em>&nbsp;(2018, Anthony Russo, Joe Russo)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5.- MORGAN FREEMAN<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 4 mil 522 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>Batman: el caballero de la noche<\/em>&nbsp;(2008, Christopher Nolan)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4.- TOM HANKS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 4 mil 606 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:\u00a0<em>Toy Story 3<\/em>\u00a0(2010, Lee Unkrich)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.- ROBERT DOWNEY JR.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 4 mil 960 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>Avengers: Infinity War<\/em>&nbsp;(2018, Anthony Russo, Joe Russo)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.- HARRISON FORD<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 4 mil 963 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:&nbsp;<em>Star Wars: Episodio VII \u2013 El despertar de la Fuerza<\/em>&nbsp;(2015, J.J. Abrams)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.- SAMUEL L. JACKSON<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recaudaci\u00f3n: 5 mil 576 billones de d\u00f3lares<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pel\u00edcula m\u00e1s taquillera:\u00a0<em>Avengers: Infinity War<\/em>\u00a0(2018, Anthony Russo, Joe Russo)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> sinembargo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico.- Sagas de \u00e9xito como las de El se\u00f1or de los anillos,\u00a0Harry Potter\u00a0o las\u00a0pel\u00edculas de Marvel\u00a0han hecho historia en el s\u00e9ptimo arte. Y no por su repercusi\u00f3n mundial y argumentos que est\u00e1n en boca de todos, que tambi\u00e9n, sino por las cantidades imposibles de\u00a0dinero\u00a0que han ofrecido a actores como Samuel L. Jackson, Robert [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":84380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-84379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/84379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=84379"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/84379\/revisions"}],"predecessor-version":[{"id":84381,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/84379\/revisions\/84381"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/84380"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=84379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=84379"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=84379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}