{"id":86815,"date":"2021-01-16T12:15:39","date_gmt":"2021-01-16T17:15:39","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=86815"},"modified":"2021-01-16T12:15:40","modified_gmt":"2021-01-16T17:15:40","slug":"bloqueo-carretero-permanente-en-tihosuco-reclaman-ejidatarios-indemnizacion-de-100-mdp-por-expropiacion-de-casi-100-hectareas-en-fcp","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/varios\/bloqueo-carretero-permanente-en-tihosuco-reclaman-ejidatarios-indemnizacion-de-100-mdp-por-expropiacion-de-casi-100-hectareas-en-fcp\/","title":{"rendered":"BLOQUEO CARRETERO PERMANENTE EN TIHOSUCO: Reclaman ejidatarios indemnizaci\u00f3n de 100 mdp por expropiaci\u00f3n de casi 100 hect\u00e1reas en FCP"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>FELIPE CARRILLO PUERTO, MX.-&nbsp;<\/strong>Ante el incumplimiento de las autoridades de los compromisos asumidos en las reuniones de trabajo, ejidatarios de Tihosuco bloquearon por cuarta ocasi\u00f3n la carretera que conduce a Valladolid para reiterar la exigencia del pago de casi 100 hect\u00e1reas expropiadas por la Secretar\u00eda de Comunicaciones y Transportes (SCT) hace m\u00e1s de 46 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este viernes reinici\u00f3 el movimiento de protesta en espera que las autoridades federales cubran un importe aproximado a los 100 millones de pesos por el usufructo del terreno y anunciaron que ser\u00e1 permanente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ejidatarios colocaron piedras, maderas y troncos a lo ancho de la carretera lo que ocasion\u00f3 largas filas de automovilistas que no pudieran saltar la barricada. Aunque aquellos automovilistas que demuestran que requieren atenci\u00f3n m\u00e9dica son dejados transitar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente del Comisariado Ejidal de Tihosuco, Alfredo Tun Batun, manifest\u00f3 que ya no ceder\u00e1n porque est\u00e1n cansados de mentiras pues en la reuni\u00f3n que tuvieron en octubre con autoridades de la Secretar\u00eda de Comunicaciones y Transportes se acord\u00f3 que la indemnizaci\u00f3n proceder\u00eda antes de finalizar el 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que el a\u00f1o pasado realizaron tres bloqueos y en todas las ocasiones sed accedi\u00f3 a levantar el movimiento ante las promesas de las autoridades estatales y federales, de cubrir el pago que se exige por el uso de las tierras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, durante la asamblea realizada el s\u00e1bado se decidi\u00f3 nuevamente bloquear la carretera en forma permanente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Representantes de la Secretar\u00eda de Gobierno acudieron a dialogar con los inconformes pero no cedieron pues exigen el pago de las hect\u00e1reas expropiadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los inconformes manifestaron que ejidatarios de Felipe Carrillo Puerto ya recibieron sus pagos por la afectaci\u00f3n que tendr\u00e1n sus tierras por el paso del Tren Maya y los de Tihosuco siguen esperando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elementos de la Guardia Nacional intervinieron para recomendar a automovilistas seguir v\u00edas alternas para continuar con su camino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente: <\/strong>Noticaribe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FELIPE CARRILLO PUERTO, MX.-&nbsp;Ante el incumplimiento de las autoridades de los compromisos asumidos en las reuniones de trabajo, ejidatarios de Tihosuco bloquearon por cuarta ocasi\u00f3n la carretera que conduce a Valladolid para reiterar la exigencia del pago de casi 100 hect\u00e1reas expropiadas por la Secretar\u00eda de Comunicaciones y Transportes (SCT) hace m\u00e1s de 46 a\u00f1os. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":86816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-86815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varios"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/86815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=86815"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/86815\/revisions"}],"predecessor-version":[{"id":86817,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/86815\/revisions\/86817"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/86816"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=86815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=86815"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=86815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}