{"id":89225,"date":"2021-03-25T20:36:22","date_gmt":"2021-03-26T01:36:22","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=89225"},"modified":"2021-03-25T20:36:24","modified_gmt":"2021-03-26T01:36:24","slug":"como-levantar-a-la-oposicion-mexicana","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/editorial\/como-levantar-a-la-oposicion-mexicana\/","title":{"rendered":"C\u00f3mo levantar a la oposici\u00f3n mexicana"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La oposici\u00f3n a L\u00f3pez Obrador est\u00e1 derrotada. No se levanta. Y urge que se levanten. La rendici\u00f3n de cuentas requiere que los ciudadanos tengamos alternativas. Morena carga 326.000 muertos y la peor crisis econ\u00f3mica en 90 a\u00f1os. Aun as\u00ed, el 44% de los electores piensan votar por ellos. Y el PAN, la segunda fuerza, tiene un 10% del voto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay quien piensa que la oposici\u00f3n debe enfatizar los errores de Andr\u00e9s Manuel L\u00f3pez Obrador para levantarse. No es as\u00ed. Las personas conocen bien esos errores. Encuestas muestran que la mayor\u00eda de los mexicanos cree que el presidente ha manejado mal la violencia, los feminicidios y las obras de infraestructura. En cada materia, desde econom\u00eda y corrupci\u00f3n, hasta el combate a la pobreza y manejo de la pandemia, los mexicanos que piensan que su desempe\u00f1o ha sido malo, superan por mucho a los que piensan que lo ha hecho bien. En contraste, el 63% aprueba a L\u00f3pez Obrador como presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros piensan que es necesario que la oposici\u00f3n sea como L\u00f3pez Obrador. Sus votantes, dicen, son unos resentidos en busca de venganza contra la \u00e9lite. Por ello, se lamentan, solo los candidatos que puedan vocalizar la revancha contra los ricos podr\u00e1n derrotarlo. Tampoco es cierto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los mexicanos s\u00ed est\u00e1n (justificadamente) en contra de las \u00e9lites. De acuerdo con el Estudio Nacional Electoral mexicano (ENEM), el 70% cree que la \u201cmafia del poder\u201d s\u00ed existe, y el 88% que M\u00e9xico est\u00e1 gobernado por unos cuantos grupos poderosos en su propio beneficio, como ha mostrado el Latinobar\u00f3metro. En general, dos terceras partes de los mexicanos tienen tendencias populistas, entendidas como concebir a la pol\u00edtica como una lucha entre el pueblo bueno y las \u00e9lites corruptas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, eso no quiere decir que solo quieran votar por quien vocaliza revanchas. De hecho, el voto de los mexicanos propopulistas se dividi\u00f3 pr\u00e1cticamente en proporciones iguales entre el PAN, PRI y Morena en 2018. Como han expuesto Paul Beck, profesor em\u00e9rito de la Ohio State University y de Gerardo Maldonado, profesor del CIDE, solo el 21% de los votantes de L\u00f3pez Obrador ten\u00edan tendencias populistas, no muy diferente que la de Anaya que fue del 15%, o que las de otros candidatos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es decir, la b\u00fasqueda de venganza contra la \u00e9lite no explica el voto por Morena. A la oposici\u00f3n le gusta creer eso porque los reconforta. Los hace sentir como la alternativa racional de los votantes educados. Aunque ello tampoco es cierto. Un estudio reciente del World Inequality Database, muestra que entre m\u00e1s educadas son las personas, m\u00e1s votan por Morena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, hay quien piensa que el problema es la percepci\u00f3n de la corrupci\u00f3n. El PRI y el PAN cargan muchos esc\u00e1ndalos. Y s\u00ed, todo indica que los votantes creen que el PRI y el PAN son m\u00e1s corruptos que Morena, pero nuevamente, ello no explica el voto. Las investigadoras Melina Altamirano y Sandra Ley del CIDE han identificado que las personas que m\u00e1s cre\u00edan que hab\u00eda aumentado la corrupci\u00f3n durante el sexenio de Pe\u00f1a Nieto no votaron m\u00e1s por L\u00f3pez Obrador. Es decir, la corrupci\u00f3n no fue un factor determinante para la victoria de Morena en 2018.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El problema real por el que la oposici\u00f3n no se levanta es que, a diferencia de L\u00f3pez Obrador, no tienen un diagn\u00f3stico sustantivo, estructural, cre\u00edble y claro sobre qu\u00e9 est\u00e1 causando las desigualdades y la falta de desarrollo de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oposici\u00f3n acepta que las cosas est\u00e1n mal y propone cambios en pol\u00edtica p\u00fablica para avanzar. Pero no puede explicar por qu\u00e9 llevamos d\u00e9cadas haciendo cambios en pol\u00edtica p\u00fablica, muchos de esos cambios propuestos por la oposici\u00f3n misma cuando estaba en el Gobierno, sin avanzar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Morena s\u00ed tiene un diagn\u00f3stico: el Gobierno era un comit\u00e9 al servicio unos pocos, un lugar de excesos y favoritismos. El resultado era que los cambios en pol\u00edtica p\u00fablica, aun si eran buenos en papel, en la realidad terminaban siendo implementados para favorecer a los amigos de los poderosos. O para no tocarlos. En este M\u00e9xico no importaba qu\u00e9 pol\u00edtica p\u00fablica se propusiera, siempre se encontraba la manera de que los beneficiados fueran los mismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, M\u00e9xico era casa de los programas sociales m\u00e1s premiados del mundo, pero no por ello se lograba reducir la pobreza de manera significativa. Las reformas estructurales se aprobaron, pero no aument\u00f3 la clase media. El sistema fiscal se reform\u00f3, pero quienes terminaron pagando m\u00e1s impuestos fueron las clases medias altas, no los ultrarricos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez Obrador es popular porque diagnostic\u00f3, no las pol\u00edticas p\u00fablicas que se necesitan, sino la raz\u00f3n por la cual las pol\u00edticas p\u00fablicas, no importa cu\u00e1les sean, no han funcionado en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oposici\u00f3n carece de un discurso as\u00ed de poderoso. Su conclusi\u00f3n es que M\u00e9xico necesita deshacerse de L\u00f3pez Obrador y de Pe\u00f1a Nieto. Y ya. No se les ocurre o no saben qu\u00e9 hacer para transformar a M\u00e9xico. Y lo peor es que el rid\u00edculo de Ricardo Anaya anda todos los d\u00edas demostrando que, en efecto, fue candidato a la presidencia sin conocer a M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las mejores mentes dentro de la oposici\u00f3n deben abocarse a honestamente evaluar por qu\u00e9 M\u00e9xico es la d\u00e9cima quinta econom\u00eda m\u00e1s grande del mundo, un miembro de la OCDE, y el socio comercial m\u00e1s importante de Estados Unidos, y aun as\u00ed tiene al 38% de los trabajadores sin poder alimentar a sus familias. El PRI y el PAN deben meditar sobre por qu\u00e9, habiendo estado en el poder, no pudieron cambiar eso. Y sobre todo, deben honestamente decirnos qu\u00e9 van a hacer diferente esta vez. Y qui\u00e9n, de los que estaban con ellos, ya nunca estar\u00e1n a su lado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El problema es que hacer esto requiere mucho m\u00e1s que contratar consultores caros. Requiere un cambio profundo que las \u00e9lites partidistas del PAN y del PRI no est\u00e1n dispuestas a hacer porque, como en todo M\u00e9xico, los cotos de poder han colonizado sus partidos. A nivel local la pol\u00edtica es un negocio familiar. El cambio que el PRI y el PAN requieren hacer para ganar es cortar de tajo con esas familias y hacer pol\u00edtica de base otra vez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> elpa\u00eds<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La oposici\u00f3n a L\u00f3pez Obrador est\u00e1 derrotada. No se levanta. Y urge que se levanten. La rendici\u00f3n de cuentas requiere que los ciudadanos tengamos alternativas. Morena carga 326.000 muertos y la peor crisis econ\u00f3mica en 90 a\u00f1os. Aun as\u00ed, el 44% de los electores piensan votar por ellos. Y el PAN, la segunda fuerza, tiene [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":89226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"class_list":["post-89225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editorial"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/89225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=89225"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/89225\/revisions"}],"predecessor-version":[{"id":89227,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/89225\/revisions\/89227"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/89226"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=89225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=89225"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=89225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}