{"id":89246,"date":"2021-03-26T09:12:05","date_gmt":"2021-03-26T14:12:05","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=89246"},"modified":"2021-03-26T09:12:07","modified_gmt":"2021-03-26T14:12:07","slug":"cae-en-chiapas-presunta-asesina-de-una-mujer-en-playa-del-carmen","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/policiacas\/cae-en-chiapas-presunta-asesina-de-una-mujer-en-playa-del-carmen\/","title":{"rendered":"Cae en Chiapas presunta asesina de una mujer en Playa del Carmen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General del Estado de Quintana Roo en colaboraci\u00f3n con autoridades ministeriales del estado de Chiapas, cumplimentaron una orden de aprehensi\u00f3n contra Estrella \u201cG\u201d por el delito de homicidio en agravio de una mujer de identidad reservada ocurrido en abril del a\u00f1o 2019 en el municipio de Solidaridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a las primeras investigaciones, el 5 de abril del 2019, Estrella \u201cG\u201d probablemente deton\u00f3 un arma de fuego en varias ocasiones en contra de una v\u00edctima de identidad reservada cuando ambas se encontraban en una reuni\u00f3n social; derivado de las lesiones causadas por impactos de bala, la v\u00edctima perdi\u00f3 la vida y la imputada se dio a la fuga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras las investigaciones, Estrella \u201cG\u201d fue ubicada en el poblado de Comalapa, en el estado de Chiapas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese lugar, las autoridades ministeriales lograron la captura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue trasladada a Quintana Roo, ingresada al CERESO de Solidaridad y puesta a disposici\u00f3n de la autoridad que la requiere para que defina su situaci\u00f3n jur\u00eddica en los plazos que marca la ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente: <\/strong>marcrixnoticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General del Estado de Quintana Roo en colaboraci\u00f3n con autoridades ministeriales del estado de Chiapas, cumplimentaron una orden de aprehensi\u00f3n contra Estrella \u201cG\u201d por el delito de homicidio en agravio de una mujer de identidad reservada ocurrido en abril del a\u00f1o 2019 en el municipio de Solidaridad. De acuerdo a las primeras investigaciones, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":89247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-89246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiacas"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/89246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=89246"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/89246\/revisions"}],"predecessor-version":[{"id":89248,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/89246\/revisions\/89248"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/89247"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=89246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=89246"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=89246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}