{"id":89249,"date":"2021-03-26T09:42:39","date_gmt":"2021-03-26T14:42:39","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=89249"},"modified":"2021-03-26T09:42:40","modified_gmt":"2021-03-26T14:42:40","slug":"muere-mujer-en-cancun-tras-someterse-a-una-cirugia-estetica","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/policiacas\/muere-mujer-en-cancun-tras-someterse-a-una-cirugia-estetica\/","title":{"rendered":"Muere mujer en Canc\u00fan tras someterse a una cirug\u00eda est\u00e9tica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una mujer de 38 a\u00f1os de edad, identificada como L.Y.L, muri\u00f3 antes de ingresar al Hospital Azura, antes \u201cVictoria\u201d, ubicada en la avenida Sunyanxch\u00e9n, manzana 6 lote 59, luego de haberse sometido a un procedimiento est\u00e9tico en la cl\u00ednica particular Mivera el d\u00eda de ayer mi\u00e9rcoles 24 de marzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a los primeros informes los hechos ocurrieron a las 10:00 horas, cuando se report\u00f3 al n\u00famero de emergencias 911, que en la Supermanzana 25, este jueves 25 de marzo hab\u00eda muerto una mujer, luego de haberse practicado una lipoescultura y una abdominoplastia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, hoy cerca de las 9:00 horas la doctora Martha Patricia P.F, le mencion\u00f3 a los familiares que el procedimiento se les complic\u00f3 un poco y que iban a trasladar a su esposa a la cl\u00ednica Victoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como primer respondiente llegaron elementos de la Polic\u00eda Quintana Roo a bordo de la unidad 5927, quienes confirmaron el deceso de la mujer, quien en vida respond\u00eda al nombre de L.Y.L, de 38 a\u00f1os de edad, originaria del Estado de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La hoy occisa fue reconocida por su hermana y su pareja sentimental, quienes se\u00f1alaron que la cl\u00ednica les inform\u00f3 que debido a una complicaci\u00f3n habr\u00edan solicitado una ambulancia para trasladarla de emergencia a otro lugar para brindarle la atenci\u00f3n m\u00e9dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando lleg\u00f3 a la Cl\u00ednica Azura le estaban dando maniobras de reanimaci\u00f3n por lo que a petici\u00f3n de la doctora P.P., donde lleg\u00f3 sin signos vitales por lo que se negaron a recibirla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de una mujer de complexi\u00f3n media, tez clara, cabello casta\u00f1o, de aproximadamente 1.70 metros de estatura, sin vestimenta las cuales presentaba las siguiente lesiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mujer presentaba una herida suturada alrededor de los pezones, una herida suturada en la regi\u00f3n p\u00e9lvica de aproximadamente 60 cent\u00edmetros y una herida suturada en la regi\u00f3n dorsal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente: <\/strong>marcrixnoticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una mujer de 38 a\u00f1os de edad, identificada como L.Y.L, muri\u00f3 antes de ingresar al Hospital Azura, antes \u201cVictoria\u201d, ubicada en la avenida Sunyanxch\u00e9n, manzana 6 lote 59, luego de haberse sometido a un procedimiento est\u00e9tico en la cl\u00ednica particular Mivera el d\u00eda de ayer mi\u00e9rcoles 24 de marzo. De acuerdo a los primeros informes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":89250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-89249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiacas"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/89249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=89249"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/89249\/revisions"}],"predecessor-version":[{"id":89251,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/89249\/revisions\/89251"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/89250"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=89249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=89249"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=89249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}