{"id":91287,"date":"2021-05-31T12:16:38","date_gmt":"2021-05-31T17:16:38","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=91287"},"modified":"2021-05-31T12:16:40","modified_gmt":"2021-05-31T17:16:40","slug":"contra-morena-pri-proyecta-alianza-opositora-para-2024","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/destacadas\/contra-morena-pri-proyecta-alianza-opositora-para-2024\/","title":{"rendered":"Contra Morena, PRI proyecta alianza opositora para 2024"},"content":{"rendered":"\n<p>La&nbsp;<strong>secretaria general del Partido Revolucionario Institucional (PRI), Carolina Viggiano<\/strong>, abri\u00f3 la puerta a formar una gran&nbsp;<strong>coalici\u00f3n opositora para recuperar la Presidencia en 2024.<\/strong><\/p>\n\n\n\n<p>El PRI concurrir\u00e1 por primera vez en las elecciones intermedias del pr\u00f3ximo 6 de junio con la in\u00e9dita&nbsp;<strong>alianza Va por M\u00e9xico<\/strong>, junto al&nbsp;<strong>PAN y el PRD<\/strong>, algo que podr\u00eda \u00abrepetir\u00bb en las presidenciales si logra buenos resultados frente a Morena.<\/p>\n\n\n\n<p>\u00abS\u00ed se puede repetir. Vamos a esperar a los resultados y si funciona seguramente podr\u00edamos analizar la posibilidad de repetir una alianza de este tipo\u00bb, dijo Viggiano en su despacho en la sede del partido.<\/p>\n\n\n\n<p>La secretaria general dijo que el PRI ya est\u00e1 haciendo \u00abproyecciones\u00bb con la mirada puesta en 2024 y cree que \u00abla sociedad se ha dado cuenta\u00bb de que su partido gobierna \u00abmejor\u00bb y tiene \u00abm\u00e1s experiencia\u00bb. Pero no detall\u00f3 qui\u00e9n deber\u00eda ser el candidato presidencial de la oposici\u00f3n.<\/p>\n\n\n\n<p>\u00abLlegado el momento tocar\u00e1 revisar qui\u00e9nes tienen los perfiles m\u00e1s competitivos para encabezar y seamos capaces con generosidad de construir una alianza ganadora\u00bb, opin\u00f3.<\/p>\n\n\n\n<p>Por ahora, los esfuerzos est\u00e1n centrados en el 6 de junio, cuando m\u00e1s de 93 millones de mexicanos est\u00e1n llamados a las urnas para renovar la C\u00e1mara de Diputados, 15 de los 32 gobernadores, 30 congresos locales y mil 900 ayuntamientos en lo que se consideran las elecciones m\u00e1s grandes de la historia de M\u00e9xico.<\/p>\n\n\n\n<p>\u00abNuestra expectativa es conquistar m\u00e1s espacios en la C\u00e1mara de Diputados. Por eso construimos una alianza que no fue sencilla con partidos como el PAN o el PRD que fueron nuestros adversarios, sin embargo, nos uni\u00f3 rescatar este pa\u00eds del desastre\u00bb, dijo Viggiano, mano derecha del presidente del PRI, Alejandro Moreno.<\/p>\n\n\n\n<p>Viggiano critic\u00f3 que la mayor\u00eda parlamentaria en manos de Morena y sus aliados desde 2018 tiene \u00abun \u00e1nimo autoritario de poder\u00bb y se ha convertido \u00aben una aplanadora\u00bb en casi todas las votaciones.<\/p>\n\n\n\n<p>\u00abEl gobierno federal todos los d\u00edas busca dividir y polarizar, nos debilita como naci\u00f3n. Eso les puede hacer ganar porque dividen el pa\u00eds en dos y se quedan una parte\u00bb, lament\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s, denunci\u00f3 que los planes de austeridad del gobierno han afectado a las mujeres, a los enfermos de c\u00e1ncer, entre otros, y arremeti\u00f3 contra la gesti\u00f3n de la pandemia, que ha situado a M\u00e9xico como cuarto en el mundo en n\u00famero de muertos.<\/p>\n\n\n\n<p><strong>Fuente: <\/strong>heraldodemexico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La&nbsp;secretaria general del Partido Revolucionario Institucional (PRI), Carolina Viggiano, abri\u00f3 la puerta a formar una gran&nbsp;coalici\u00f3n opositora para recuperar la Presidencia en 2024. El PRI concurrir\u00e1 por primera vez en las elecciones intermedias del pr\u00f3ximo 6 de junio con la in\u00e9dita&nbsp;alianza Va por M\u00e9xico, junto al&nbsp;PAN y el PRD, algo que podr\u00eda \u00abrepetir\u00bb en las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":91289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-91287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/91287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=91287"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/91287\/revisions"}],"predecessor-version":[{"id":91290,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/91287\/revisions\/91290"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/91289"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=91287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=91287"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=91287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}