{"id":92814,"date":"2021-07-19T09:34:24","date_gmt":"2021-07-19T14:34:24","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=92814"},"modified":"2021-07-19T09:34:25","modified_gmt":"2021-07-19T14:34:25","slug":"nfl-tom-brady-y-los-buccaneers-visitaran-a-joe-biden-en-la-casa-blanca","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/entretenimiento\/deportes\/nfl-tom-brady-y-los-buccaneers-visitaran-a-joe-biden-en-la-casa-blanca\/","title":{"rendered":"NFL: Tom Brady y los Buccaneers visitar\u00e1n a Joe Biden en la Casa Blanca"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La pr\u00f3xima semana, los Tampa Bay Buccaneers visitar\u00e1n la Casa Blanca de Washington D. C. para reunirse con Joe Biden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de los Estados Unidos invit\u00f3 a los jugadores del equipo comandado por Bruce Arians para felicitarlos por haber conseguido el campeonato de la temporada 2020 de la NFL.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a un funcionario, que habl\u00f3 bajo la condici\u00f3n de anonimato al anticiparse al anuncio oficial, la reuni\u00f3n se llevar\u00e1 a cabo el martes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Super Bowl LV, los Tampa Bay Buccaneers derrotaron por un contundente marcador de 31-9 a los Kansas City Chiefs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tom Brady hizo historia al ganar su s\u00e9ptimo anillo, pues anteriormente gan\u00f3 seis con los New England Patriots. Patrick Mahomes tuvo una noche para el olvido en el Raymond James Stadium.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Weeknd fue el gran protagonsita del show de medio tiempo e interpret\u00f3 \u00e9xitos como \u201cBlinding Lights\u201d y \u201cSave Your Rears\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una traici\u00f3n que cada a\u00f1o el presidente de los Estados Unidos se re\u00fana con los mejores equipos la NFL, NBA, MLB, MLS y NHL.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las visitas fueron espor\u00e1dicas durante el mandato de Donald Trump, pero se espera que sean m\u00e1s frecuentes ahora que est\u00e1 Joe Biden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De hecho, hace unas semanas, Julio Urias y V\u00edctor Gonz\u00e1lez recibieron un reconocimiento en la Casa Blanca, luego de que los Angeles Dodgers derrotaron a los Tampa Bay Rays en la Serie Mundial de la temporada 2020 de las Grandes Ligas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> Heraldo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pr\u00f3xima semana, los Tampa Bay Buccaneers visitar\u00e1n la Casa Blanca de Washington D. C. para reunirse con Joe Biden. El presidente de los Estados Unidos invit\u00f3 a los jugadores del equipo comandado por Bruce Arians para felicitarlos por haber conseguido el campeonato de la temporada 2020 de la NFL. De acuerdo a un funcionario, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":92815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-92814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/92814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=92814"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/92814\/revisions"}],"predecessor-version":[{"id":92816,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/92814\/revisions\/92816"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/92815"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=92814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=92814"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=92814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}