{"id":94187,"date":"2021-08-29T10:52:17","date_gmt":"2021-08-29T15:52:17","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=94187"},"modified":"2021-08-29T10:52:19","modified_gmt":"2021-08-29T15:52:19","slug":"tenia-19-anos-cuando-fui-reclutada-relata-una-sobreviviente-de-la-secta-nxivm","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/destacadas\/tenia-19-anos-cuando-fui-reclutada-relata-una-sobreviviente-de-la-secta-nxivm\/","title":{"rendered":"\u201cTen\u00eda 19 a\u00f1os cuando fui reclutada\u201d, relata una sobreviviente de la secta NXIVM"},"content":{"rendered":"\n<p><strong>India Oxenberg<\/strong>, hija de la&nbsp;<strong>actriz estadounidense Catherine Oxenberg<\/strong>, revel\u00f3 este jueves en una entrevista para la revista&nbsp;<em>People<\/em>&nbsp;c\u00f3mo acab\u00f3 involucrada en la&nbsp;<strong>secta NXIVM<\/strong>, con sede en Albany (Nueva York), que reclutaba esclavas sexuales.<\/p>\n\n\n\n<p>De 30 a\u00f1os al d\u00eda de hoy, la mujer detall\u00f3 que fue incorporada a una divisi\u00f3n dependiente de la organizaci\u00f3n, llamada \u201cDOS\u201d (acr\u00f3nimo en lat\u00edn que alude a un maestro de compa\u00f1eras obedientes), por la actriz Allison Mack, quien fue condenada el pasado junio a tres a\u00f1os de prisi\u00f3n por liderar esa filial junto con Lauren Salzman.<\/p>\n\n\n\n<p><strong>\u201cESAS PERSONAS PAREC\u00cdAN TENERLO TODO RESUELTO\u201d<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cYo ten\u00eda 19 a\u00f1os cuando fui reclutada por miembros de una secta llamada NXIVM\u201d, record\u00f3 la denunciante, y a\u00f1adi\u00f3 que en aquel momento se sent\u00eda \u201csin direcci\u00f3n\u201d y \u201cmal preparada para la vida independiente\u201d, por lo que \u201cbuscaba una orientaci\u00f3n\u201d. \u201cPens\u00e9 que necesitaba saber ciertas cosas sobre m\u00ed misma para avanzar con mis metas y sue\u00f1os\u201d, dijo, y crey\u00f3 entonces que esa organizaci\u00f3n podr\u00eda guiarla para \u201cser m\u00e1s fuerte y m\u00e1s capaz\u201d de iniciar una peque\u00f1a empresa propia y ayudarla en su propio \u201cautodescubrimiento\u201d.<\/p><\/blockquote>\n\n\n\n<p>Al recordar su experiencia, Oxenberg afirm\u00f3 que no le fue dif\u00edcil \u201cconfiar en ellos\u201d al principio. \u201cEsas personas parec\u00edan tenerlo todo resuelto\u201d, explic\u00f3 al medio. \u201cEran inteligentes, exitosos y carism\u00e1ticos. Eran todo lo que yo quer\u00eda para m\u00ed. Poco sab\u00eda, en aquel momento, que esa fachada era uno de los muchos productos y empresas de consumo que se utilizan para atraer, captar y reclutar nuevos miembros\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>\u201cLos reclutas estaban desprotegidos y eran maleables, pero tambi\u00e9n eran personas que aportaban valor\u201d, dijo. \u201cLo m\u00e1s complicado de todo era que, desde fuera, mucho de aquello pod\u00eda pasar como una empresa normal, aparentemente leg\u00edtima, con quiz\u00e1 algunas pr\u00e1cticas no convencionales\u201d.<\/p>\n\n\n\n<p><strong>CUALQUIERA PUEDE SER VULNERABLE A LA MANIPULACI\u00d3N<\/strong><\/p>\n\n\n\n<p>Oxenberg sostuvo que \u201cfue preparada por el l\u00edder de NXIVM\u201d, Keith Raniere, a trav\u00e9s de sus miembros de mayor rango y recibi\u00f3 \u201cla educaci\u00f3n que ellos ense\u00f1aban\u201d. \u201cNo fue hasta que entr\u00e9 en el grupo de mayor control que \u00e9l realmente tuvo acceso sexual a m\u00ed, debido al chantaje y el&nbsp;<em>grooming<\/em>&nbsp;hecho por Allison Mack\u201d, detall\u00f3. \u201cEso me convirti\u00f3 en un blanco m\u00e1s f\u00e1cil para ese tipo de abuso, porque \u00e9l sab\u00eda que yo no quer\u00eda ni pod\u00eda decirle nada a nadie. Dos de esos a\u00f1os los pas\u00e9 en un c\u00edrculo interno a\u00fan m\u00e1s controlado dentro de la organizaci\u00f3n, que manten\u00eda el secreto mediante el chantaje, la extorsi\u00f3n y la desestabilizaci\u00f3n de sus v\u00edctimas o reclutas, hasta el punto de que \u00e9ramos incapaces de tomar decisiones propias y sensatas\u201d, declar\u00f3.<\/p>\n\n\n\n<p>La mujer subray\u00f3 que espera que su historia sirva de ejemplo de c\u00f3mo cualquiera puede ser vulnerable a la \u201cmanipulaci\u00f3n\u201d. \u201cCuando alguien intenta coaccionarte, es dif\u00edcil ver la realidad de la situaci\u00f3n, est\u00e1s condicionado (\u2026) para cuestionar tus propios instintos\u201d, dijo.<\/p>\n\n\n\n<p>\u201cEsto crea confusi\u00f3n y caos, y resulta dif\u00edcil saber en qui\u00e9n confiar cuando la persona principal \u2013t\u00fa mismo\u2013 ya no es un lugar seguro al que volver. Todo tu mundo se convierte en apoyo para las mentiras de los perpetradores, mientras ellos intentan disminuir tu valor y confianza en tu capacidad para tomar decisiones fuera de las mentiras que te est\u00e1n contando\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Oxenberg apunt\u00f3 que, en su caso, los l\u00edderes de la secta trataron de \u201cnormalizar el sexo y la intimidad\u201d como parte de sus \u201cdeberes\u201d con el grupo, dici\u00e9ndole que sus problemas ten\u00edan que ver con la intimidad y que \u201cno ten\u00eda la opci\u00f3n de no \u2018completar la tarea&#8217;\u201d.<\/p>\n\n\n\n<p><strong>\u201cCUANDO EL ABUSO OCURRE, NO ES TU CULPA\u201d<\/strong><\/p>\n\n\n\n<p>Seg\u00fan asever\u00f3 la v\u00edctima, actualmente se encuentra en un camino de curaci\u00f3n. Revel\u00f3 que despu\u00e9s de dejar NXIVM y procesar sus experiencias, hubo momentos en los que sinti\u00f3 \u201cverg\u00fcenza y culpa\u201d, \u201cemociones a las que se enfrentan muchos supervivientes despu\u00e9s de sufrir abusos o violencia sexual\u201d.<\/p>\n\n\n\n<p>La mujer detall\u00f3 que una de las cosas m\u00e1s importantes que ha aprendido, y que quiere compartir, es que \u201ccuando el abuso ocurre, no es tu culpa\u201d. \u201cNo importa lo que lleves, en qui\u00e9n conf\u00edes, si bebes o est\u00e1s en una fiesta, no hay nada que puedas hacer para merecer experimentar la violencia. La verg\u00fcenza, la culpa y el reproche son siempre de los agresores\u201d, destac\u00f3.<\/p>\n\n\n\n<p>\u201cTanto si has sufrido violencia sexual en el campus de tu universidad como si te ha ocurrido con un grupo de confianza de la comunidad, no es culpa tuya, y es importante que te cuides despu\u00e9s de haber sufrido un trauma. Ya sea que haya ocurrido recientemente o hace a\u00f1os, el autocuidado puede ayudarte a enfrentar los efectos a corto y largo plazo de un trauma como la agresi\u00f3n sexual\u201d, concluy\u00f3.<\/p>\n\n\n\n<p><strong>\u00bfQU\u00c9 ES NXIVM?<\/strong><\/p>\n\n\n\n<p>Fundada en 1998 por Keith Raniere y Nancy Salzman, la secta NXIVM pretend\u00eda ser una organizaci\u00f3n de&nbsp;<em>marketing&nbsp;<\/em>multinivel que ofrec\u00eda cursos y seminarios de desarrollo personal y profesional. Desde los a\u00f1os 90, se estima que alrededor de 16 mil personas han participado en sus diferentes \u201cprogramas de capacitaci\u00f3n\u201d.<\/p>\n\n\n\n<p>La mayor\u00eda de ellos tomaron cursos que efectivamente los ayudaron a superar problemas psicol\u00f3gicos. Sin embargo, otras personas, al involucrarse m\u00e1s profundamente en NXIVM, acabaron renunciando a sus carreras, amigos y familias para convertirse en fieles seguidores de su l\u00edder, Keith Raniere, conocido dentro del grupo como \u201cVanguard\u201d o \u201cGrandmaster\u201d.<\/p>\n\n\n\n<p>En 2018, despu\u00e9s de varios intentos fallidos de exmiembros para iniciar un proceso legal contra Raniere, se abri\u00f3 finalmente una investigaci\u00f3n basada en denuncias de tr\u00e1fico sexual, conspiraci\u00f3n para trabajo sexual y conspiraci\u00f3n para trabajo forzado en contra de mujeres. El gur\u00fa fundador de la organizaci\u00f3n huy\u00f3 a M\u00e9xico, pero all\u00ed fue detenido, deportado a EU y, en octubre del 2019, sentenciado a 120 a\u00f1os de prisi\u00f3n.<\/p>\n\n\n\n<p>Durante la investigaci\u00f3n, que dur\u00f3 m\u00e1s de a\u00f1o y medio, la Justicia estadounidense acumul\u00f3 tambi\u00e9n informaci\u00f3n exhaustiva sobre los delitos de otros miembros de alto rango de la secta, que \u201cfueron conscientes y facilitaron el comportamiento delictivo\u201d del l\u00edder del grupo.<\/p>\n\n\n\n<p>Uno de ellos era Clare Bronfman, hija del multimillonario Edgar Bronfman, expresidente de la compa\u00f1\u00eda canadiense Seagram, qui\u00e9n fue sentenciada en 2020 a seis a\u00f1os y nueve meses de prisi\u00f3n. Mientras, Lauren Salzman, l\u00edder de alto rango de DOS, fue condenada a cinco a\u00f1os de libertad condicional y 300 horas de servicio comunitario, tras evitar una sentencia mucho mayor gracias a su colaboraci\u00f3n con las autoridades<\/p>\n\n\n\n<p>NXIVM tiene representaci\u00f3n en M\u00e9xico, donde opera a trav\u00e9s de \u201cExecutive Success Programs\u201d (ESP o Programas de \u00c9xito Ejecutivo, en espa\u00f1ol).<\/p>\n\n\n\n<p><strong>Fuente:<\/strong>&nbsp;sinembargo<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>India Oxenberg, hija de la&nbsp;actriz estadounidense Catherine Oxenberg, revel\u00f3 este jueves en una entrevista para la revista&nbsp;People&nbsp;c\u00f3mo acab\u00f3 involucrada en la&nbsp;secta NXIVM, con sede en Albany (Nueva York), que reclutaba esclavas sexuales. De 30 a\u00f1os al d\u00eda de hoy, la mujer detall\u00f3 que fue incorporada a una divisi\u00f3n dependiente de la organizaci\u00f3n, llamada \u201cDOS\u201d (acr\u00f3nimo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":94188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-94187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/94187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=94187"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/94187\/revisions"}],"predecessor-version":[{"id":94189,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/94187\/revisions\/94189"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/94188"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=94187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=94187"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=94187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}