{"id":97680,"date":"2021-11-13T12:58:11","date_gmt":"2021-11-13T17:58:11","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=97680"},"modified":"2021-11-13T12:58:43","modified_gmt":"2021-11-13T17:58:43","slug":"obligar-a-los-ninos-a-comer-uno-de-los-origenes-de-los-trastornos-alimentarios","status":"publish","type":"post","link":"http:\/\/elcuartopoder.com.mx\/nw\/entretenimiento\/salud\/obligar-a-los-ninos-a-comer-uno-de-los-origenes-de-los-trastornos-alimentarios\/","title":{"rendered":"Obligar a los ni\u00f1os a comer, uno de los or\u00edgenes de los trastornos alimentarios"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La psic\u00f3loga Pilar Conde explica c\u00f3mo abordar esta cuesti\u00f3n para evitar riesgos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ha perdido peso de forma significativa. Est\u00e1 deca\u00eddo, nervioso y se comporta de manera extra\u00f1a en la mesa y despu\u00e9s de comer. Compra demasiados dulces y chucher\u00edas para picar entre horas o ha dejado de&nbsp;<strong>consumir alimentos cal\u00f3ricos que antes le encantaban<\/strong>. Estos son algunos indicios que pueden hacerte sospechar que tu hijo est\u00e1 padeciendo un trastorno de la conducta alimentaria. Lo que debes hacer es actuar r\u00e1pido, aunque sea para descartarlo, porque, si es verdad que existe dicho problema, es important\u00edsimo evitar que se convierta en una conducta habitual y se cronifique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora bien, matiza la psic\u00f3loga\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/clinicasorigen.es\/\" target=\"_blank\">Pilar Conde,<\/a>\u00a0puede suceder que una intervenci\u00f3n familiar inicial, sin la asesor\u00eda de un experto, resulte contraproducente, ya que es habitual que al plantear el tema en casa se produzcan situaciones conflictivas, sobre todo, con adolescentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo correcto en estos casos es buscar primero la asesor\u00eda m\u00e9dica y despu\u00e9s, conjuntamente, si es posible, abordar el problema con un equipo interdisciplinar nutricionista-psic\u00f3logo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es, ni mucho menos, un camino f\u00e1cil. Es un proceso duro y largo, porque, tal como explica directora t\u00e9cnica de Cl\u00ednicas Origen,&nbsp;<strong>no s\u00f3lo se trata de modificar los h\u00e1bitos de alimentaci\u00f3n<\/strong>&nbsp;que est\u00e1n perjudicando su salud de manera muy grave. El problema tiene una ra\u00edz emocional y psicol\u00f3gica que hay que abordar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La clave es encontrar el origen del trastorno y de qu\u00e9 manera lo est\u00e1 manteniendo la persona.&nbsp;<strong>El enfoque puede hacerse desde la identificaci\u00f3n de los sentimientos<\/strong>&nbsp;y los pensamientos que le han llevado a los desajustes en su manera de relacionarse con la comida y con su imagen corporal. Tambi\u00e9n mediante la toma de conciencia de su manera de comportarse y de hacia d\u00f3nde le conduce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esa reestructuraci\u00f3n cognitiva se complementa<strong>&nbsp;ense\u00f1ando al paciente a identificar los distintos tipos de hambre&nbsp;<\/strong>y orient\u00e1ndole hacia t\u00e9cnicas que le ayuden en su lucha contra la enfermedad.&nbsp;<strong>El mindfull eating<\/strong>, comer siendo conscientes de qu\u00e9 ingerimos y de qu\u00e9 manera lo estamos haciendo, es una de ellas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En casa, la labor debe centrarse en&nbsp;<strong>la elaboraci\u00f3n de men\u00fas saludables<\/strong>. Los productos hipercal\u00f3ricos que puedan dar lugar a atracones deben ser eliminados de la lista de la compra. Tambi\u00e9n es relevante que se mantengan unas pautas de horarios en las comidas y que se elimine la posibilidad de comer en el sof\u00e1, en bandejas, y de picar entre horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con respecto a la conveniencia de que el joven o adolescente afectado haga p\u00fablico su problema en su entorno cercano, depender\u00e1 de c\u00f3mo quiera afrontarlo, en base a sus creencias y valores, aclara Pilar Conde. \u00abEs un tema que se suele abordar en terapia y es el paciente quien decide como gestionarlo\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Autoestima<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La autoestima, tanto en los problemas de sobrepeso como de infrapeso, es clave en este asunto, como lo es en todo el&nbsp;<strong>desarrollo psicol\u00f3gico y emocional de ni\u00f1os y adolescentes<\/strong>. Este \u00faltimo grupo es uno de los m\u00e1s afectados por los denominados TCA \u2014anorexia, bulimia, trastorno por atrac\u00f3n, trastorno por evitaci\u00f3n y vigorexia \u2014, y durante la pandemia ha visto aumentar su incidencia, a la vez que disminu\u00eda la edad de los afectados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El aislamiento f\u00edsico que supuso el confinamiento trajo consigo un incremento notable de los niveles de ansiedad y estr\u00e9s en toda la poblaci\u00f3n, pero de manera espec\u00edfica en los adolescentes y los j\u00f3venes. Algunos expertos suman a este factor la&nbsp;<strong>r<\/strong>ealizaci\u00f3n de ejercicio de manera intensiva durante a trav\u00e9s de tutoriales on line o el seguimiento de dietas en las redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos pueden haber sido factores desencadenantes, pero el origen puede estar en una&nbsp;<strong>mala regulaci\u00f3n de los estados emocionales desde la propia ni\u00f1ez.<\/strong>&nbsp;En este caso, a trav\u00e9s de la comida. Por eso, explican desde esta red de cl\u00ednicas, es importante que en nuestro aprendizaje y desarrollo personal se incluya la capacidad introspectiva, con el fin de conocer qu\u00e9 hay tras nuestras conductas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Obligar a un ni\u00f1o a comer si no tiene ganas o no le gusta la comida pueda ser uno de los<strong>&nbsp;or\u00edgenes de la bulimia,<\/strong>&nbsp;la anorexia o sobrepeso. Aunque no es un factor determinante, aclara Conde, debe ser considerado porque en la infancia se comienzan a forjar los primeros h\u00e1bitos de alimentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, los padres deben saber que n<strong>o es bueno que el ni\u00f1o deje el plato vac\u00edo en contra de sus deseos<\/strong>&nbsp;y de su apetito. Lo \u00f3ptimo es que deje de comer cuando se sienta saciado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tampoco se deber\u00e1 ser muy permisivo en cuanto a la ingesta de chucher\u00edas, bollos, helados y, en definitiva, todo lo que les encanta, pero resulta<strong>&nbsp;malo para la salud si lo consumen en exceso<\/strong>. \u00abEs necesario inculcar una alimentaci\u00f3n saludable, tanto en productos como en n\u00famero de veces y ah\u00ed si que el menor podr\u00e1 relacionarse de manera adecuada con las sensaciones de su cuerpo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, mucho cuidado, si las dietas entran en la vida de tu hijo, si no es por motivos de salud, en casos de sobrepeso y obesidad. Son un\u00a0<strong>indicio claro de descontento con la imagen corporal\u00a0<\/strong>y un peligro de que un trastorno de la conducta alimentaria ha entrado o est\u00e1 a punto de entrar en su vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por:  <a>ABC Familia<\/a> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">fuente: https:\/\/www.abc.es\/familia\/padres-hijos\/abci-obligar-ninos-comer-origenes-trastornos-alimentarios-202111100114_noticia.html<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La psic\u00f3loga Pilar Conde explica c\u00f3mo abordar esta cuesti\u00f3n para evitar riesgos Ha perdido peso de forma significativa. Est\u00e1 deca\u00eddo, nervioso y se comporta de manera extra\u00f1a en la mesa y despu\u00e9s de comer. Compra demasiados dulces y chucher\u00edas para picar entre horas o ha dejado de&nbsp;consumir alimentos cal\u00f3ricos que antes le encantaban. Estos son [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":97681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62,56],"tags":[],"class_list":["post-97680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","category-salud"],"_links":{"self":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/97680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=97680"}],"version-history":[{"count":1,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/97680\/revisions"}],"predecessor-version":[{"id":97682,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/97680\/revisions\/97682"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/97681"}],"wp:attachment":[{"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=97680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=97680"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=97680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}