{"id":132584,"date":"2024-09-18T10:34:48","date_gmt":"2024-09-18T15:34:48","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=132584"},"modified":"2024-09-18T10:34:53","modified_gmt":"2024-09-18T15:34:53","slug":"bolsas-de-nicotina-alto-riesgo-de-adiccion-y-dano-a-la-salud-para-la-ninez-expertos","status":"publish","type":"post","link":"https:\/\/elcuartopoder.com.mx\/nw\/entretenimiento\/salud\/bolsas-de-nicotina-alto-riesgo-de-adiccion-y-dano-a-la-salud-para-la-ninez-expertos\/","title":{"rendered":"Bolsas de nicotina, alto riesgo de adicci\u00f3n y da\u00f1o a la salud para la ni\u00f1ez: expertos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las bolsas de nicotina representan un alto riesgo de adicci\u00f3n y da\u00f1o a la salud para ni\u00f1as, ni\u00f1os y adolescentes, pues se presenta como un nuevo mecanismo de suministro de nicotina, una de las sustancias m\u00e1s adictivas, y que en menores de edad puede tener efectos en el adecuado desarrollo del cerebro, la memoria y la capacidad de aprendizaje, alertaron expertos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conferencia de prensa, Erick Antonio Ochoa, directora de Salud Justa MX, detall\u00f3 que se trata de productos que no cumplen con las normas mexicana de protecci\u00f3n a los derechos del consumidor, pues carecen de informaci\u00f3n b\u00e1sica como datos sobre su producci\u00f3n, cantidad que se debe consumir y el riesgo que puede representar para la salud de los consumidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De reciente aparici\u00f3n en el mercado mexicano, las bolsas de nicotina est\u00e1n dirigidas, advirti\u00f3 Maximiliano C\u00e1rdenas, coordinador jur\u00eddico de Salud Justa Mx, a la poblaci\u00f3n infantil y adolescente, pese a que se trata de un \u00abproducto completamente adictivo que no tiene leyendas de advertencia, se publicita en establecimientos comerciales y est\u00e1 al alcance de todos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de un producto, indic\u00f3, elaborado con nicotina sint\u00e9tica, a la que le han a\u00f1adido cuatro saborizantes, \u00abde los que tampoco se informa nada, y se dise\u00f1a para impactar un mercado de ni\u00f1os y adolescentes. Su forma de consumo, es meterlo a la boca, pero no hay ninguna advertencia de qu\u00e9 pasar\u00eda su la bolsa llega a romperse y se tiene contacto directo con el producto, a trav\u00e9s de la mucosa oral\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La doctora Guadalupe Ponciano Rodr\u00edguez, coordinadora del Comit\u00e9 Interinstitucional para la Lucha contra el Tabaco, alert\u00f3 sobre los graves riesgos a la salud en la poblaci\u00f3n de ni\u00f1os y adolescentes, y destac\u00f3 que a la fecha se desconoce si las empresas que los comercializan cuentan con los permisos de ley para introducir estos productos al mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, exhortaron a las autoridades sanitarias a que se pronuncien sobre las bolsas de nicotina y se inform\u00e9 \u00abc\u00f3mo obtuvieron permisos para su comercializaci\u00f3n, si es que acaso los tienen, y que se alerte a la poblaci\u00f3n, en particular a ni\u00f1os y adolescentes sobre el riesgo de consumo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En agosto pasado, la Comisi\u00f3n Nacional de Salud Mental y Adicciones (Conasama) de la Secretar\u00eda de Salud, emiti\u00f3 una alerta ante el riesgo que representa su uso, especialmente en adolescentes y j\u00f3venes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El organismo p\u00fablico destaca que la producci\u00f3n de dichas bolsas \u00abson una t\u00e1ctica m\u00e1s de la industria tabacalera para atraer y mantener el consumo en adolescentes y j\u00f3venes, de manera similar a lo realizado con los cigarros de sabor o cigarros electr\u00f3nicos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su dise\u00f1o \u00ablos hace especialmente peligrosos para los menores, debido a que se pueden ocultar f\u00e1cilmente. Los productos con nicotina pueden da\u00f1ar el desarrollo del cerebro de adolescentes y afectar la atenci\u00f3n, el aprendizaje y la memoria. Adem\u00e1s, aumentan el riesgo de enfermedades cardiacas y pueden intensificar los s\u00edntomas de depresi\u00f3n y ansiedad\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las bolsas de nicotina representan un alto riesgo de adicci\u00f3n y da\u00f1o a la salud para ni\u00f1as, ni\u00f1os y adolescentes, pues se presenta como un nuevo mecanismo de suministro de nicotina, una de las sustancias m\u00e1s adictivas, y que en menores de edad puede tener efectos en el adecuado desarrollo del cerebro, la memoria y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":132585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-132584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"_links":{"self":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/132584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=132584"}],"version-history":[{"count":1,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/132584\/revisions"}],"predecessor-version":[{"id":132586,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/132584\/revisions\/132586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/132585"}],"wp:attachment":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=132584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=132584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=132584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}