{"id":147560,"date":"2026-07-15T11:44:59","date_gmt":"2026-07-15T16:44:59","guid":{"rendered":"https:\/\/elcuartopoder.com.mx\/nw\/?p=147560"},"modified":"2026-07-15T11:45:01","modified_gmt":"2026-07-15T16:45:01","slug":"la-esperanza-de-mexico-se-derrumbo","status":"publish","type":"post","link":"https:\/\/elcuartopoder.com.mx\/nw\/destacadas\/la-esperanza-de-mexico-se-derrumbo\/","title":{"rendered":"La esperanza de M\u00e9xico se derrumb\u00f3"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En 2018, L\u00f3pez Obrador y su partido vendieron como marca electoral \u201cLa esperanza de M\u00e9xico\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dice el dicho popular que la esperanza es lo \u00faltimo que se pierde, pero cuando se construye sobre promesas vac\u00edas y t\u00e1cticas err\u00f3neas, es lo primero que se derrumba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la pol\u00edtica, como en el f\u00fatbol, el activo m\u00e1s valioso es la ilusi\u00f3n, la confianza y la esperanza de la gente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En 2018, L\u00f3pez Obrador<\/strong>&nbsp;y su partido vendieron como marca electoral \u201cLa esperanza de M\u00e9xico\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada cuatro a\u00f1os, la Selecci\u00f3n Nacional nos vende la ilusi\u00f3n de que, esta vez, s\u00ed se cambiar\u00e1 la historia, de que el \u201cquinto partido\u201d est\u00e1 al alcance de la mano y de que, aunque sea en un 1%, estaba la posibilidad de ser campeones del mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, a casi ocho a\u00f1os de distancia (seis de&nbsp;<strong>L\u00f3pez Obrador y dos de Claudia Sheinbaum),<\/strong>&nbsp;la realidad pol\u00edtica es id\u00e9ntica a la de nuestro futbol: la esperanza de M\u00e9xico se derrumb\u00f3 dram\u00e1ticamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo pol\u00edtico, por obras a sobreprecio, por un presupuesto sin resultados, por la alta corrupci\u00f3n en el c\u00edrculo cercano de L\u00f3pez Obrador, por una tensa relaci\u00f3n con Estados Unidos, por la poca atenci\u00f3n en el combate a la delincuencia y por gobernar sin estrategia cometiendo grandes errores al privilegiar la lealtad a la capacidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo deportivo, por errores t\u00e1cticos, necedad desde el banquillo y fallas garrafales de los jugadores, ante un equipo de primer nivel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la pol\u00edtica y en el futbol, los resultados dependen del diagn\u00f3stico correcto y la ejecuci\u00f3n clara, basada en la estrategia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aqu\u00ed fallaron ambos:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la pol\u00edtica, la necedad de L\u00f3pez Obrador que prefiri\u00f3 la polarizaci\u00f3n sobre el respeto a la pluralidad; que prefiri\u00f3 la construcci\u00f3n de sus obras \u201ccapricho\u201d a la terminaci\u00f3n de las obras iniciadas; que privilegi\u00f3 la lealtad sobre la capacidad; que destruy\u00f3 las instituciones democr\u00e1ticas y los \u00f3rganos constitucionales aut\u00f3nomos y que por solapar la corrupci\u00f3n en su c\u00edrculo familiar, termin\u00f3 por derrumbar \u201cLa esperanza de M\u00e9xico\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el futbol, la necedad del entrenador que prefiri\u00f3 un modelo de ataque poco efectivo hacia el final del partido, sumado a dos errores defensivos claros que terminaron por derrumbar \u201cLa esperanza de M\u00e9xico\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Selecci\u00f3n Nacional nos demostr\u00f3 que la esperanza sin estrategia nos dej\u00f3 fuera en los octavos de final y el gobierno actual nos demuestra que \u201cLa esperanza de M\u00e9xico\u201d fue un eslogan de campa\u00f1a, no un plan de gobierno que los puede dejar fuera en el corto plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ambos casos, los platos rotos los paga la afici\u00f3n, es decir, los ciudadanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro de 4 a\u00f1os, en el 2030, se podr\u00e1 reavivar \u201cLa esperanza de M\u00e9xico\u201d en los dos frentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo pol\u00edtico habr\u00e1 elecciones presidenciales y en lo deportivo, se celebrar\u00e1 un nuevo campeonato mundial de futbol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pregunta es: \u00bfcon los mismos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">POR HUMBERTO AGUILAR CORONADO POLIT\u00d3LOGO<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Heraldo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2018, L\u00f3pez Obrador y su partido vendieron como marca electoral \u201cLa esperanza de M\u00e9xico\u201d Dice el dicho popular que la esperanza es lo \u00faltimo que se pierde, pero cuando se construye sobre promesas vac\u00edas y t\u00e1cticas err\u00f3neas, es lo primero que se derrumba. En la pol\u00edtica, como en el f\u00fatbol, el activo m\u00e1s valioso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":147561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-147560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"_links":{"self":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/147560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=147560"}],"version-history":[{"count":1,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/147560\/revisions"}],"predecessor-version":[{"id":147562,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/147560\/revisions\/147562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/147561"}],"wp:attachment":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=147560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=147560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=147560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}