{"id":77162,"date":"2020-03-02T11:40:53","date_gmt":"2020-03-02T16:40:53","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=77162"},"modified":"2020-03-02T11:40:55","modified_gmt":"2020-03-02T16:40:55","slug":"consejos-psicologicos-ante-el-coronavirus-vacunas-para-evitar-el-panico","status":"publish","type":"post","link":"https:\/\/elcuartopoder.com.mx\/nw\/entretenimiento\/salud\/consejos-psicologicos-ante-el-coronavirus-vacunas-para-evitar-el-panico\/","title":{"rendered":"Consejos psicol\u00f3gicos ante el coronavirus: \u00abvacunas\u00bb para evitar el p\u00e1nico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En medio del contexto que vivimos en la actualidad, sabemos que&nbsp;<strong>no hay virus m\u00e1s peligroso que el propio miedo.&nbsp;<\/strong>Basta con dar un repaso a nuestras redes sociales para ver c\u00f3mo las noticias fluyen casi a cada segundo, llen\u00e1ndonos de temor y hasta de p\u00e1nico. Ahora bien, en medio de este escenario de inquietud no hay mejor vacuna que unos buenos consejos psicol\u00f3gicos ante el coronavirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Organismos como la<em>&nbsp;American Psychological Association<\/em>&nbsp;(APA) nos informan de que entre la poblaci\u00f3n, ya se ha instalado otro tipo de infecci\u00f3n casi m\u00e1s peligrosa que la enfermedad de la que todo el mundo habla:<strong>&nbsp;la ansiedad ante el propio coronavirus.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La compra de mascarillas y desinfectantes se ha disparado<\/strong>, nos asustamos cuando alguien estornuda cerca de nosotros y estamos incluso, alterando nuestros h\u00e1bitos de vida. Son muchos los que, por ejemplo,\u00a0se lo piensan dos veces antes de subir a un avi\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00bfEstamos llevando al l\u00edmite esta situaci\u00f3n?&nbsp;<em>Tal vez.<\/em>&nbsp;\u00bfEs exagerado experimentar miedo en miedo de este contexto?&nbsp;<em>No, no lo es.<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Sentir temor e inquietud ante la presencia de un nuevo virus es l\u00f3gico y comprensible. No obstante,&nbsp;<strong>el miedo debe actuar siempre como sistema de alerta y no de alarma<\/strong>. Debe ayudarnos a reaccionar de manera razonable y l\u00f3gica y no a trav\u00e9s del p\u00e1nico, del comportamiento irracional. Es as\u00ed como damos lo mejor de nosotros mismos y es as\u00ed como hacemos frente a cualquier problema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lograrlo, reaccionar de manera adecuada a las circunstancias que vivimos ahora mismo, exige de nosotros tener en cuenta una serie de consejos muy concretos.<em>&nbsp;Profundicemos.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lamenteesmaravillosa.com\/wp-content\/uploads\/2020\/02\/muestra-coronavirus.jpg\" alt=\"muestras de sangre representando los consejos psicol\u00f3gicos ante el coronavirus\" class=\"wp-image-225736\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">3 consejos psicol\u00f3gicos ante el coronavirus<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hay quien dice que el \u00a0COVID-19\u00a0ha sido el \u00faltimo en salir de la caja de Pandora de los virus. Es posible que as\u00ed sea, no obstante, algo que tambi\u00e9n estaba presente en esta m\u00edtica caja creada por Hefesto por orden de Zeus, era la esperanza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No podemos olvidar que nuestros sistemas sanitarios est\u00e1n bien preparados<\/strong>&nbsp;y que llevamos d\u00e9cadas haciendo frente a m\u00faltiples enfermedades y epidemias como lo fueron el SARS o el MERS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed,\u00a0algo que se\u00f1alan expertos como el acad\u00e9mico Baruch Fischhoff, miembro de la\u00a0<em>American Psychological Association<\/em>\u00a0(APA) y experto en percepci\u00f3n del riesgo y ciencia de la conducta, es que estas situaciones exigen lo mejor de nosotros mismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan sus propias palabras:&nbsp;<em><strong>\u00aben situaciones de crisis las personas deben unirse, apoyarse mutuamente y actuar con valent\u00eda<\/strong>. Si nos dejamos llevar por el p\u00e1nico, nos privamos de la oportunidad de actuar de manera coordinada\u00bb.&nbsp;<\/em>Veamos por tanto cu\u00e1les son los consejos psicol\u00f3gicos ante el coronavirus que deber\u00edamos tener en cuenta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. La sobreinformaci\u00f3n aboca a la preocupaci\u00f3n excesiva: regulemos el tiempo de exposici\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hay im\u00e1genes que activan en nosotros el miedo,<\/strong>&nbsp;pero no se trata de un miedo cualquiera, es ese temor at\u00e1vico que provocan palabras como \u00abpandemia\u00bb, \u00abinfecci\u00f3n\u00bb,\u00abvirus\u00bb, etc. Asimismo, im\u00e1genes de m\u00e9dicos completamente vestidos con sus trajes protectores y personas ataviadas con mascarillas generan de inmediato en nosotros una sensaci\u00f3n de alarma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si a esos est\u00edmulos le a\u00f1adimos la sobreinformaci\u00f3n a la que estamos sometidos,<strong>&nbsp;es casi inevitable que el miedo, se vuelva en alg\u00fan momento casi irracional.<\/strong>&nbsp;Sabemos que estamos expuestos a un gran n\u00famero de informaci\u00f3n y que esta se comparte al segundo, que basta con encender la radio o la televisi\u00f3n para que la palabra \u00abcoronavirus\u00bb surja al momento.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Consejo:<\/strong>\u00a0controlemos nuestros tiempos de exposici\u00f3n y consulta sobre este tema. Debemos hacer vida normal procurando que las noticias sobre el coronavirus orbiten de manera continuada a lo largo de nuestras jornadas. Busquemos fuentes oficiales y evitemos la infoxicaci\u00f3n. Asimismo,\u00a0ante la preocupaci\u00f3n excesiva, lo mejor es dedicar tiempo\u00a0a esas actividades que m\u00e1s nos interesen, relajen o distraigan.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lamenteesmaravillosa.com\/wp-content\/uploads\/2020\/02\/bulos-coronavirus.jpg\" alt=\"Bulo representando los consejos psicol\u00f3gicos ante el coronavirus\" class=\"wp-image-225737\"\/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2. La desinformaci\u00f3n es el peor de los virus: hay que vacunarse ante los bulos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Otro de los consejos psicol\u00f3gicos\u00a0ante el coronavirus que debemos tener en cuenta son los bulos<strong>. No hay virus m\u00e1s letal que la desinformaci\u00f3n<\/strong>, esa que infecta el p\u00e1nico de manera inmediata y casi a golpe de\u00a0<em>click<\/em>\u00a0y noticia compartida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En los \u00faltimos d\u00edas, hemos recibido informaci\u00f3n como que el agua salada previene el contagio del COVID-19.<\/strong>&nbsp;Hemos visto im\u00e1genes manipuladas de grupos de personas en el suelo haci\u00e9ndonos creer que eran fallecidos en las calles de Wuhan. Nos han informado incluso de que Bill Gates tiene la patente de este tipo de coronavirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No faltan tampoco las teor\u00edas conspiratorias que indican que el n\u00famero de fallecidos es m\u00e1s alto del que nos dicen, que el virus ha sido liberado a prop\u00f3sito por Estados Unidos o Rusia con el fin de destabilizar la econom\u00eda\u2026<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Consejo:\u00a0<\/strong>tengamos en cuenta una sencilla regla, esa que nos advierte de que<strong>\u00a0cerca del 40 % de las noticias que recibimos son falsas<\/strong>. La informaci\u00f3n veraz es la aut\u00e9ntica vacuna ante estas situaciones y exige de nosotros que seamos cautos y previsores ante cada cosa que leemos.\u00a0Busquemos fuentes serias, como es sin duda la de la Organizaci\u00f3n Mundial de la Salud.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">3. La calma es la mejor aliada: en alerta pero no en alarma<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ante el virus del p\u00e1nico, mejor la calma.<\/strong>&nbsp;Ante la sensaci\u00f3n de miedo e inquietud, mejor estar en alerta que en alarma. \u00bfQu\u00e9 significa esto? Implica que las personas actuamos mucho mejor en un estado de calma psicol\u00f3gica. Ello no significa en absoluto que debamos sentirnos indiferentes ante las noticias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se trata solo de mantenernos atentos a lo que sucede sin experimentar ese miedo irracional<\/strong>&nbsp;que nos aboca a conductas sin sentido que no ayudan.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Consejo:<\/strong>&nbsp;uno de los consejos psicol\u00f3gicos ante el coronavirus m\u00e1s b\u00e1sicos es&nbsp;<strong>seguir desarrollando una vida normal.<\/strong>&nbsp;La rutina es nuestra mejor aliada. Asimismo, es necesario consultar en alg\u00fan momento del d\u00eda cu\u00e1l es la situaci\u00f3n y el avance de la enfermedad. Debemos mantenernos receptivos y seguir la informaci\u00f3n de los expertos.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lamenteesmaravillosa.com\/wp-content\/uploads\/2019\/03\/medico-paciente.jpg\" alt=\"M\u00e9dico con paciente\" class=\"wp-image-179201\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para concluir, somos conscientes de que el&nbsp;<em>Covid-19<\/em>&nbsp;nos obliga a estar pendientes de cada informaci\u00f3n. Estamos ante un virus nuevo y algo as\u00ed, exige de&nbsp;<strong>los organismos sanitarios ir analizando al segundo c\u00f3mo act\u00faa y cu\u00e1l es su comportamiento.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por nuestra parte<strong>&nbsp;solo cabe continuar con nuestros h\u00e1bitos de vida cotidianos, seguir los consejos b\u00e1sicos de higiene&nbsp;<\/strong>y cumplir con las indicaciones que se nos pauten desde las esferas oficiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordemos una vez m\u00e1s las palabras del doctor Baruch Fischhoff:<em><strong>\u00a0toda crisis se resuelve actuando sin p\u00e1nico y de manera conjunta y coordinada<\/strong>.<\/em>\u00a0Sigamos ese valioso consejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente: <\/strong>lamenteesmaravillosa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio del contexto que vivimos en la actualidad, sabemos que&nbsp;no hay virus m\u00e1s peligroso que el propio miedo.&nbsp;Basta con dar un repaso a nuestras redes sociales para ver c\u00f3mo las noticias fluyen casi a cada segundo, llen\u00e1ndonos de temor y hasta de p\u00e1nico. Ahora bien, en medio de este escenario de inquietud no hay [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":77163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-77162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"_links":{"self":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/77162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=77162"}],"version-history":[{"count":1,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/77162\/revisions"}],"predecessor-version":[{"id":77164,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/77162\/revisions\/77164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/77163"}],"wp:attachment":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=77162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=77162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=77162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}