{"id":91183,"date":"2021-05-27T10:45:15","date_gmt":"2021-05-27T15:45:15","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=91183"},"modified":"2021-05-27T10:45:17","modified_gmt":"2021-05-27T15:45:17","slug":"inteligencia-financiera-mantendra-bloqueo-de-cuentas-de-altos-hornos-y-minera-del-norte","status":"publish","type":"post","link":"https:\/\/elcuartopoder.com.mx\/nw\/nacionales\/inteligencia-financiera-mantendra-bloqueo-de-cuentas-de-altos-hornos-y-minera-del-norte\/","title":{"rendered":"Inteligencia Financiera mantendr\u00e1 bloqueo de cuentas de Altos Hornos y Minera del Norte"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Unidad de Inteligencia Financiera (UIF) a cargo de Santiago Nieto, inform\u00f3 que mantendr\u00e1 bloqueadas las cuentas bancarias de Altos Hornos de M\u00e9xico y la empresa Minera del Norte, luego de que les fue negado un amparo, mientras que, en el caso de Rafael \u201cZ\u201d, interpondr\u00e1 un recurso de revisi\u00f3n para mantener sus cuentas congeladas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado, la UIF inform\u00f3 que fueron notificados sobre la negativa que emiti\u00f3 el Juzgado Cuarto de Distrito del Estado de Coahuila sobre el amparo que Altos Hornos de M\u00e9xico y la empresa Minera del Norte promovieron para la liberaci\u00f3n de sus recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo anterior, ya que&nbsp;la UIF demostr\u00f3 que orden\u00f3 la inmovilizaci\u00f3n de cuentas bancarias como una medida cautelar&nbsp;relacionada con el cumplimiento a compromisos internacionales asumidos por nuestro pa\u00eds, as\u00ed como en prevenci\u00f3n a la comisi\u00f3n y\/o continuaci\u00f3n del delito de operaciones con recursos de procedencia il\u00edcita\u201d, indica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de que este mi\u00e9rcoles el juez d\u00e9cimo cuarto de Distrito en Materia Administrativa, V\u00edctor Octavio Luna Escobedo, concedi\u00f3 un amparo al empresario Rafael \u201cN\u201d, acusado de un presunto fraude al Infonavit y orden\u00f3 el desbloqueo de sus cuentas, la UIF se\u00f1al\u00f3 que se apegar\u00e1 al proceso de todos estos casos e interpondr\u00e1 una impugnaci\u00f3n, por lo que no liberar\u00e1 las cuentas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa Unidad de Inteligencia Financiera, perteneciente a la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico, informa una vez que sea notificada la sentencia que otorga el amparo a Rafael &#8216;Z&#8217; en el t\u00e9rmino legal, la UIF interpondr\u00e1 recurso de revisi\u00f3n, para que sea un Tribunal Colegiado del primer circuito quien estudie en \u00faltima instancia la constitucionalidad del bloqueo de cuentas\u201d, apunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> XEU<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Unidad de Inteligencia Financiera (UIF) a cargo de Santiago Nieto, inform\u00f3 que mantendr\u00e1 bloqueadas las cuentas bancarias de Altos Hornos de M\u00e9xico y la empresa Minera del Norte, luego de que les fue negado un amparo, mientras que, en el caso de Rafael \u201cZ\u201d, interpondr\u00e1 un recurso de revisi\u00f3n para mantener sus cuentas congeladas. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":91184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-91183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/91183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=91183"}],"version-history":[{"count":1,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/91183\/revisions"}],"predecessor-version":[{"id":91185,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/91183\/revisions\/91185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/91184"}],"wp:attachment":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=91183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=91183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=91183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}