{"id":91196,"date":"2021-05-27T12:01:23","date_gmt":"2021-05-27T17:01:23","guid":{"rendered":"http:\/\/elcuartopoder.com.mx\/nw\/?p=91196"},"modified":"2021-05-27T12:01:26","modified_gmt":"2021-05-27T17:01:26","slug":"judicatura-destituye-a-juez-que-libero-a-personas-involucradas-en-acopio-de-armas","status":"publish","type":"post","link":"https:\/\/elcuartopoder.com.mx\/nw\/policiacas\/judicatura-destituye-a-juez-que-libero-a-personas-involucradas-en-acopio-de-armas\/","title":{"rendered":"Judicatura destituye a juez que liber\u00f3 a personas involucradas en acopio de armas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Consejo de la Judicatura Federal (CFJ) destituy\u00f3 al juez federal Jos\u00e9 Horta, quien estuvo adscrito a los estados de Baja California y Veracruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La destituci\u00f3n se da por no vincular a proceso y poner en libertad a diversas personas involucradas en el acopio y transporte de m\u00faltiples armas de fuego y cartuchos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n el comunicado:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Consejo de la Judicatura Federal (CJF) aprob\u00f3 hoy destituir a un Juez de Distrito por su inexcusable actuaci\u00f3n al no vincular a proceso, y con ello poner en libertad, a las personas involucradas en el acopio y transporte de m\u00faltiples armas de fuego y cartuchos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Pleno del CJF, tras una investigaci\u00f3n profunda y un debido proceso sobre el caso, determin\u00f3 que el juzgador incurri\u00f3 en un error inexcusable conforme a la normativa del Poder Judicial de la Federaci\u00f3n. Lo anterior, debido a que el juez dict\u00f3 su resoluci\u00f3n con base en un tipo penal distinto al expuesto por la Fiscal\u00eda en su acusaci\u00f3n. Con ello, el Juez actu\u00f3 en contra de constancias y se apart\u00f3 de los hechos denunciados en el caso. Una clara desviaci\u00f3n a la ley que no ser\u00e1 tolerada por el CJF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo primordial para el Pleno del CJF y su Presidente, Ministro Arturo Zald\u00edvar, es generar confianza en la ciudadan\u00eda respecto a sus juzgadoras y juzgadores. Confianza en su imparcialidad, independencia y autonom\u00eda. Parte importante de la construcci\u00f3n de esa confianza pasa por la absoluta integridad de sus servidoras y servidores p\u00fablicos y su profesionalismo. Estamos convencidos de que el servicio p\u00fablico de la procuraci\u00f3n de justicia se debe completamente al bienestar y dignidad de la gente. Y ah\u00ed, la falta de integridad no tiene cabida.<\/p>\n\n\n\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/Comunicado?src=hash&amp;ref_src=twsrc%5Etfw\">#Comunicado<\/a> Se destituye a Juez federal por actos inexcusables: actuar y resolver en contra de hechos denunciados en un caso.<br><br>Lo primordial para el CJF seguir\u00e1 siendo generar confianza en la ciudadan\u00eda respecto a la integridad y profesionalismo de sus juzgadoras y juzgadores. <a href=\"https:\/\/t.co\/34zKf0tX3v\">pic.twitter.com\/34zKf0tX3v<\/a><\/p>&mdash; CJF (@CJF_Mx) <a href=\"https:\/\/twitter.com\/CJF_Mx\/status\/1397642240240099333?ref_src=twsrc%5Etfw\">May 26, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong>&nbsp;XEU<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo de la Judicatura Federal (CFJ) destituy\u00f3 al juez federal Jos\u00e9 Horta, quien estuvo adscrito a los estados de Baja California y Veracruz. La destituci\u00f3n se da por no vincular a proceso y poner en libertad a diversas personas involucradas en el acopio y transporte de m\u00faltiples armas de fuego y cartuchos. A continuaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":91197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-91196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiacas"],"_links":{"self":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/91196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/comments?post=91196"}],"version-history":[{"count":1,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/91196\/revisions"}],"predecessor-version":[{"id":91198,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/posts\/91196\/revisions\/91198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media\/91197"}],"wp:attachment":[{"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/media?parent=91196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/categories?post=91196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcuartopoder.com.mx\/nw\/wp-json\/wp\/v2\/tags?post=91196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}